{"id":102270,"date":"2026-06-03T17:40:04","date_gmt":"2026-06-03T15:40:04","guid":{"rendered":"https:\/\/gimnasticdetarragona.cat\/?p=102270"},"modified":"2026-06-03T17:42:47","modified_gmt":"2026-06-03T15:42:47","slug":"tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona","status":"publish","type":"post","link":"https:\/\/gimnasticdetarragona.cat\/es\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\/","title":{"rendered":"Tomeu Nadal, nuevo director deportivo del Gimn\u00e0stic de Tarragona"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Gimn\u00e0stic de Tarragona ha llegado a un acuerdo con Tomeu Nadal para incorporarlo como responsable de la direcci\u00f3n deportiva de la entidad hasta el curso 2027\/2028.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El que fue portero del primer equipo durante dos temporadas y media (2013-2016) y uno de los h\u00e9roes del ascenso a Segunda Divisi\u00f3n A en la temporada 2014-2015, vuelve a Tarragona para iniciar un nuevo proyecto deportivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El manacorense llega libre a Tarragona despu\u00e9s de finalizar su vinculaci\u00f3n con el CD Castell\u00f3n, equipo de LaLiga Hypermotion, donde ha ejercido las tareas de <em>recruitment assistant<\/em> en la secretar\u00eda t\u00e9cnica del filial albinegro y apoyo a la estructura deportiva del primer equipo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tomeu Nadal compagin\u00f3 su carrera futbol\u00edstica y la formaci\u00f3n acad\u00e9mica profesional cursando el Grado en Derecho y Ciencias Pol\u00edticas, entre otras titulaciones como el Master Global Players Performance de LaLiga y el MBA en Direcci\u00f3n y Administraci\u00f3n de Empresas por la ISEB. Adem\u00e1s de completar el Curso Superior Universitario de Director Deportivo por la RFEF.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esta primera incorporaci\u00f3n para el nuevo curso 2026\/2027, el Gimn\u00e0stic de Tarragona muestra su total confianza en un t\u00e9cnico con proyecci\u00f3n, profesional, experto en sistemas de scouting actuales y con ra\u00edces en la entidad grana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El exmeta grana vuelve a Tarragona firmando un contrato por dos temporadas<\/p>\n","protected":false},"author":7,"featured_media":102268,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[113,126],"tags":[],"class_list":["post-102270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-primer-equipo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tomeu Nadal, nuevo director deportivo del Gimn\u00e0stic de Tarragona - Gimn\u00e0stic de Tarragona SAD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gimnasticdetarragona.cat\/es\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tomeu Nadal, nuevo director deportivo del Gimn\u00e0stic de Tarragona - Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"og:description\" content=\"El exmeta grana vuelve a Tarragona firmando un contrato por dos temporadas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gimnasticdetarragona.cat\/es\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\/\" \/>\n<meta property=\"og:site_name\" content=\"Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-03T15:40:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-03T15:42:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2026\/06\/dfv.jpg.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicacion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:site\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicacion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\\\/\"},\"author\":{\"name\":\"Comunicacion\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/0a9b7103e7dd73640eb245c4aa4afb8d\"},\"headline\":\"Tomeu Nadal, nuevo director deportivo del Gimn\u00e0stic de Tarragona\",\"datePublished\":\"2026-06-03T15:40:04+00:00\",\"dateModified\":\"2026-06-03T15:42:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\\\/\"},\"wordCount\":227,\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/dfv.jpg.jpeg\",\"articleSection\":[\"Actualidad\",\"Primer Equipo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\\\/\",\"name\":\"Tomeu Nadal, nuevo director deportivo del Gimn\u00e0stic de Tarragona - Gimn\u00e0stic de Tarragona SAD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/dfv.jpg.jpeg\",\"datePublished\":\"2026-06-03T15:40:04+00:00\",\"dateModified\":\"2026-06-03T15:42:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/dfv.jpg.jpeg\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/dfv.jpg.jpeg\",\"width\":1000,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tomeu Nadal, nuevo director deportivo del Gimn\u00e0stic de Tarragona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"name\":\"Gimn\u00e0stic de Tarragona SAD\",\"description\":\"Gimn\u00e0stic de Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\",\"name\":\"GIMN\u00c0STIC DE TARRAGONA\",\"alternateName\":\"N\u00c0STIC\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"width\":224,\"height\":83,\"caption\":\"GIMN\u00c0STIC DE TARRAGONA\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/NASTICTARRAGONA\",\"https:\\\/\\\/www.instagram.com\\\/nastictarragona\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/0a9b7103e7dd73640eb245c4aa4afb8d\",\"name\":\"Comunicacion\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tomeu Nadal, nuevo director deportivo del Gimn\u00e0stic de Tarragona - Gimn\u00e0stic de Tarragona SAD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gimnasticdetarragona.cat\/es\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\/","og_locale":"es_ES","og_type":"article","og_title":"Tomeu Nadal, nuevo director deportivo del Gimn\u00e0stic de Tarragona - Gimn\u00e0stic de Tarragona SAD","og_description":"El exmeta grana vuelve a Tarragona firmando un contrato por dos temporadas","og_url":"https:\/\/gimnasticdetarragona.cat\/es\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\/","og_site_name":"Gimn\u00e0stic de Tarragona SAD","article_published_time":"2026-06-03T15:40:04+00:00","article_modified_time":"2026-06-03T15:42:47+00:00","og_image":[{"width":1000,"height":1200,"url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2026\/06\/dfv.jpg.jpeg","type":"image\/jpeg"}],"author":"Comunicacion","twitter_card":"summary_large_image","twitter_creator":"@NASTICTARRAGONA","twitter_site":"@NASTICTARRAGONA","twitter_misc":{"Escrito por":"Comunicacion","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gimnasticdetarragona.cat\/es\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\/#article","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\/"},"author":{"name":"Comunicacion","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/0a9b7103e7dd73640eb245c4aa4afb8d"},"headline":"Tomeu Nadal, nuevo director deportivo del Gimn\u00e0stic de Tarragona","datePublished":"2026-06-03T15:40:04+00:00","dateModified":"2026-06-03T15:42:47+00:00","mainEntityOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\/"},"wordCount":227,"publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2026\/06\/dfv.jpg.jpeg","articleSection":["Actualidad","Primer Equipo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gimnasticdetarragona.cat\/es\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\/","url":"https:\/\/gimnasticdetarragona.cat\/es\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\/","name":"Tomeu Nadal, nuevo director deportivo del Gimn\u00e0stic de Tarragona - Gimn\u00e0stic de Tarragona SAD","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\/#primaryimage"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2026\/06\/dfv.jpg.jpeg","datePublished":"2026-06-03T15:40:04+00:00","dateModified":"2026-06-03T15:42:47+00:00","breadcrumb":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gimnasticdetarragona.cat\/es\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\/#primaryimage","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2026\/06\/dfv.jpg.jpeg","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2026\/06\/dfv.jpg.jpeg","width":1000,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/gimnasticdetarragona.cat\/es\/tomeu-nadal-nuevo-director-deportivo-del-gimnastic-de-tarragona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/gimnasticdetarragona.cat\/es\/nastic\/"},{"@type":"ListItem","position":2,"name":"Tomeu Nadal, nuevo director deportivo del Gimn\u00e0stic de Tarragona"}]},{"@type":"WebSite","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website","url":"https:\/\/gimnasticdetarragona.cat\/es\/","name":"Gimn\u00e0stic de Tarragona SAD","description":"Gimn\u00e0stic de Tarragona","publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gimnasticdetarragona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization","name":"GIMN\u00c0STIC DE TARRAGONA","alternateName":"N\u00c0STIC","url":"https:\/\/gimnasticdetarragona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","width":224,"height":83,"caption":"GIMN\u00c0STIC DE TARRAGONA"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/NASTICTARRAGONA","https:\/\/www.instagram.com\/nastictarragona\/"]},{"@type":"Person","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/0a9b7103e7dd73640eb245c4aa4afb8d","name":"Comunicacion"}]}},"_links":{"self":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/102270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/comments?post=102270"}],"version-history":[{"count":1,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/102270\/revisions"}],"predecessor-version":[{"id":102271,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/102270\/revisions\/102271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media\/102268"}],"wp:attachment":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media?parent=102270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/categories?post=102270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/tags?post=102270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}