{"id":54769,"date":"2018-12-27T19:03:24","date_gmt":"2018-12-27T19:03:24","guid":{"rendered":"https:\/\/clone.gimnasticdetarragona.cat\/nastic-cordoba-cf-j20-laliga-123\/"},"modified":"2018-12-27T19:03:24","modified_gmt":"2018-12-27T19:03:24","slug":"nastic-cordoba-cf-j20-laliga-123","status":"publish","type":"post","link":"https:\/\/gimnasticdetarragona.cat\/es\/nastic-cordoba-cf-j20-laliga-123\/","title":{"rendered":"N\u00e0stic &#8211; C\u00f3rdoba CF, J20 LaLiga 1|2|3"},"content":{"rendered":"<p>El domingo 6 de enero a partir de les 18 horas el Nou Estadi vivir\u00e1 el primer partido del a\u00f1o 2019 que jugaran N\u00e0stic y C\u00f3rdoba CF, correspondiente a la jornada 20 de LaLiga 1|2|3.<\/p>\n<h4 style=\"margin-bottom: 10px; margin-top: 50px; font-weight: bold;\">Precios de las entradas<\/h4>\n<h5>[one_half]<strong>ZONA DEL CAMPO<\/strong>[\/one_half]<\/h5>\n<h5>[one_half_last]<strong>PREIO<\/strong>[\/one_half_last]<\/h5>\n<p>[divider style=\u00bbsolid\u00bb top=\u00bb4&#8243; bottom=\u00bb10&#8243;]<\/p>\n<p>[one_half]Tribuna[\/one_half]<br \/>\n[one_half_last]30 \u20ac[\/one_half_last]<\/p>\n<p>[one_half]Preferente[\/one_half]<br \/>\n[one_half_last]20 \u20ac[\/one_half_last]<\/p>\n<p>[one_half]Gol Norte \/ Gol Sur[\/one_half]<br \/>\n[one_half_last]15 \u20ac[\/one_half_last]<\/p>\n<p>[one_half]Zona Visitante[\/one_half]<br \/>\n[one_half_last]20 \u20ac[\/one_half_last]<\/p>\n<p>[divider style=\u00bbsolid\u00bb top=\u00bb4&#8243; bottom=\u00bb10&#8243;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El domingo 6 de enero a partir de les 18 horas el Nou Estadi vivir\u00e1 el primer partido del a\u00f1o 2019 que jugaran N\u00e0stic y C\u00f3rdoba CF, correspondiente a la jornada 20 de LaLiga 1|2|3.<\/p>\n","protected":false},"author":1,"featured_media":54766,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[113,126],"tags":[],"class_list":["post-54769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-primer-equipo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>N\u00e0stic - C\u00f3rdoba CF, J20 LaLiga 1|2|3 - Gimn\u00e0stic de Tarragona SAD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gimnasticdetarragona.cat\/es\/nastic-cordoba-cf-j20-laliga-123\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u00e0stic - C\u00f3rdoba CF, J20 LaLiga 1|2|3 - Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"og:description\" content=\"El domingo 6 de enero a partir de les 18 horas el Nou Estadi vivir\u00e1 el primer partido del a\u00f1o 2019 que jugaran N\u00e0stic y C\u00f3rdoba CF, correspondiente a la jornada 20 de LaLiga 1|2|3.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gimnasticdetarragona.cat\/es\/nastic-cordoba-cf-j20-laliga-123\/\" \/>\n<meta property=\"og:site_name\" content=\"Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-27T19:03:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/06001948142549.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"desarrollo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:site\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"desarrollo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic-cordoba-cf-j20-laliga-123\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic-cordoba-cf-j20-laliga-123\\\/\"},\"author\":{\"name\":\"desarrollo\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\"},\"headline\":\"N\u00e0stic &#8211; C\u00f3rdoba CF, J20 LaLiga 1|2|3\",\"datePublished\":\"2018-12-27T19:03:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic-cordoba-cf-j20-laliga-123\\\/\"},\"wordCount\":117,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic-cordoba-cf-j20-laliga-123\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/06001948142549.jpg\",\"articleSection\":[\"Actualidad\",\"Primer Equipo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic-cordoba-cf-j20-laliga-123\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic-cordoba-cf-j20-laliga-123\\\/\",\"name\":\"N\u00e0stic - C\u00f3rdoba CF, J20 LaLiga 1|2|3 - Gimn\u00e0stic de Tarragona SAD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic-cordoba-cf-j20-laliga-123\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic-cordoba-cf-j20-laliga-123\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/06001948142549.jpg\",\"datePublished\":\"2018-12-27T19:03:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic-cordoba-cf-j20-laliga-123\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic-cordoba-cf-j20-laliga-123\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic-cordoba-cf-j20-laliga-123\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/06001948142549.jpg\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/06001948142549.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic-cordoba-cf-j20-laliga-123\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"N\u00e0stic &#8211; C\u00f3rdoba CF, J20 LaLiga 1|2|3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"name\":\"Gimn\u00e0stic de Tarragona SAD\",\"description\":\"Gimn\u00e0stic de Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\",\"name\":\"GIMN\u00c0STIC DE TARRAGONA\",\"alternateName\":\"N\u00c0STIC\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"width\":224,\"height\":83,\"caption\":\"GIMN\u00c0STIC DE TARRAGONA\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/NASTICTARRAGONA\",\"https:\\\/\\\/www.instagram.com\\\/nastictarragona\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\",\"name\":\"desarrollo\",\"sameAs\":[\"https:\\\/\\\/clone.gimnasticdetarragona.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N\u00e0stic - C\u00f3rdoba CF, J20 LaLiga 1|2|3 - Gimn\u00e0stic de Tarragona SAD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gimnasticdetarragona.cat\/es\/nastic-cordoba-cf-j20-laliga-123\/","og_locale":"es_ES","og_type":"article","og_title":"N\u00e0stic - C\u00f3rdoba CF, J20 LaLiga 1|2|3 - Gimn\u00e0stic de Tarragona SAD","og_description":"El domingo 6 de enero a partir de les 18 horas el Nou Estadi vivir\u00e1 el primer partido del a\u00f1o 2019 que jugaran N\u00e0stic y C\u00f3rdoba CF, correspondiente a la jornada 20 de LaLiga 1|2|3.","og_url":"https:\/\/gimnasticdetarragona.cat\/es\/nastic-cordoba-cf-j20-laliga-123\/","og_site_name":"Gimn\u00e0stic de Tarragona SAD","article_published_time":"2018-12-27T19:03:24+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/06001948142549.jpg","type":"image\/jpeg"}],"author":"desarrollo","twitter_card":"summary_large_image","twitter_creator":"@NASTICTARRAGONA","twitter_site":"@NASTICTARRAGONA","twitter_misc":{"Escrito por":"desarrollo","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gimnasticdetarragona.cat\/es\/nastic-cordoba-cf-j20-laliga-123\/#article","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/nastic-cordoba-cf-j20-laliga-123\/"},"author":{"name":"desarrollo","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e"},"headline":"N\u00e0stic &#8211; C\u00f3rdoba CF, J20 LaLiga 1|2|3","datePublished":"2018-12-27T19:03:24+00:00","mainEntityOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/nastic-cordoba-cf-j20-laliga-123\/"},"wordCount":117,"commentCount":0,"publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/nastic-cordoba-cf-j20-laliga-123\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/06001948142549.jpg","articleSection":["Actualidad","Primer Equipo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gimnasticdetarragona.cat\/es\/nastic-cordoba-cf-j20-laliga-123\/","url":"https:\/\/gimnasticdetarragona.cat\/es\/nastic-cordoba-cf-j20-laliga-123\/","name":"N\u00e0stic - C\u00f3rdoba CF, J20 LaLiga 1|2|3 - Gimn\u00e0stic de Tarragona SAD","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/nastic-cordoba-cf-j20-laliga-123\/#primaryimage"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/nastic-cordoba-cf-j20-laliga-123\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/06001948142549.jpg","datePublished":"2018-12-27T19:03:24+00:00","breadcrumb":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/nastic-cordoba-cf-j20-laliga-123\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gimnasticdetarragona.cat\/es\/nastic-cordoba-cf-j20-laliga-123\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/nastic-cordoba-cf-j20-laliga-123\/#primaryimage","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/06001948142549.jpg","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/06001948142549.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/gimnasticdetarragona.cat\/es\/nastic-cordoba-cf-j20-laliga-123\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/gimnasticdetarragona.cat\/es\/nastic\/"},{"@type":"ListItem","position":2,"name":"N\u00e0stic &#8211; C\u00f3rdoba CF, J20 LaLiga 1|2|3"}]},{"@type":"WebSite","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website","url":"https:\/\/gimnasticdetarragona.cat\/es\/","name":"Gimn\u00e0stic de Tarragona SAD","description":"Gimn\u00e0stic de Tarragona","publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gimnasticdetarragona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization","name":"GIMN\u00c0STIC DE TARRAGONA","alternateName":"N\u00c0STIC","url":"https:\/\/gimnasticdetarragona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","width":224,"height":83,"caption":"GIMN\u00c0STIC DE TARRAGONA"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/NASTICTARRAGONA","https:\/\/www.instagram.com\/nastictarragona\/"]},{"@type":"Person","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e","name":"desarrollo","sameAs":["https:\/\/clone.gimnasticdetarragona.cat"]}]}},"_links":{"self":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/54769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/comments?post=54769"}],"version-history":[{"count":0,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/54769\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media\/54766"}],"wp:attachment":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media?parent=54769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/categories?post=54769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/tags?post=54769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}