{"id":54973,"date":"2018-11-23T17:51:48","date_gmt":"2018-11-23T17:51:48","guid":{"rendered":"https:\/\/clone.gimnasticdetarragona.cat\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\/"},"modified":"2018-11-23T17:51:48","modified_gmt":"2018-11-23T17:51:48","slug":"hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin","status":"publish","type":"post","link":"https:\/\/gimnasticdetarragona.cat\/es\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\/","title":{"rendered":"\u00abTenemos que competir como nunca lo ha hecho el N\u00e0stic\u00bb RDP de Enrique Mart\u00edn"},"content":{"rendered":"<p style=\"text-align: justify;\">El t\u00e9cnico Enrique Mart\u00edn ha comparecido ante los medios de comunicaci\u00f3n antes de la disputa de la jornada 15 ante la UD Almer\u00eda.<\/p>\n<p style=\"text-align: justify;\">El t\u00e9cnico navarro ha hablado de la importancia del partido de ma\u00f1ana, s\u00e1bado, en el Nou Estadi; un enfrentamiento que debe servir para sumar 3 puntos y empezar a escalar puestos en la clasificaci\u00f3n de LaLiga 1|2|3. El duelo donde el conjunto grana intentar\u00e1 conseguir la 3\u00aa victoria ante la afici\u00f3n se iniciar\u00e1 a las 16 horas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El t\u00e9cnico Enrique Mart\u00edn ha comparecido ante los medios de comunicaci\u00f3n antes de la disputa de la jornada 15 ante la UD Almer\u00eda.<\/p>\n","protected":false},"author":1,"featured_media":54970,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[113],"tags":[],"class_list":["post-54973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Tenemos que competir como nunca lo ha hecho el N\u00e0stic&quot; RDP de Enrique Mart\u00edn - Gimn\u00e0stic de Tarragona SAD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gimnasticdetarragona.cat\/es\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Tenemos que competir como nunca lo ha hecho el N\u00e0stic&quot; RDP de Enrique Mart\u00edn - Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"og:description\" content=\"El t\u00e9cnico Enrique Mart\u00edn ha comparecido ante los medios de comunicaci\u00f3n antes de la disputa de la jornada 15 ante la UD Almer\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gimnasticdetarragona.cat\/es\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\/\" \/>\n<meta property=\"og:site_name\" content=\"Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-23T17:51:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/06001901141376.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"desarrollo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:site\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"desarrollo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\\\/\"},\"author\":{\"name\":\"desarrollo\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\"},\"headline\":\"\u00abTenemos que competir como nunca lo ha hecho el N\u00e0stic\u00bb RDP de Enrique Mart\u00edn\",\"datePublished\":\"2018-11-23T17:51:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\\\/\"},\"wordCount\":100,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/06001901141376.jpg\",\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\\\/\",\"name\":\"\\\"Tenemos que competir como nunca lo ha hecho el N\u00e0stic\\\" RDP de Enrique Mart\u00edn - Gimn\u00e0stic de Tarragona SAD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/06001901141376.jpg\",\"datePublished\":\"2018-11-23T17:51:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/06001901141376.jpg\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/06001901141376.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abTenemos que competir como nunca lo ha hecho el N\u00e0stic\u00bb RDP de Enrique Mart\u00edn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"name\":\"Gimn\u00e0stic de Tarragona SAD\",\"description\":\"Gimn\u00e0stic de Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\",\"name\":\"GIMN\u00c0STIC DE TARRAGONA\",\"alternateName\":\"N\u00c0STIC\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"width\":224,\"height\":83,\"caption\":\"GIMN\u00c0STIC DE TARRAGONA\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/NASTICTARRAGONA\",\"https:\\\/\\\/www.instagram.com\\\/nastictarragona\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\",\"name\":\"desarrollo\",\"sameAs\":[\"https:\\\/\\\/clone.gimnasticdetarragona.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Tenemos que competir como nunca lo ha hecho el N\u00e0stic\" RDP de Enrique Mart\u00edn - Gimn\u00e0stic de Tarragona SAD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gimnasticdetarragona.cat\/es\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\/","og_locale":"es_ES","og_type":"article","og_title":"\"Tenemos que competir como nunca lo ha hecho el N\u00e0stic\" RDP de Enrique Mart\u00edn - Gimn\u00e0stic de Tarragona SAD","og_description":"El t\u00e9cnico Enrique Mart\u00edn ha comparecido ante los medios de comunicaci\u00f3n antes de la disputa de la jornada 15 ante la UD Almer\u00eda.","og_url":"https:\/\/gimnasticdetarragona.cat\/es\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\/","og_site_name":"Gimn\u00e0stic de Tarragona SAD","article_published_time":"2018-11-23T17:51:48+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/06001901141376.jpg","type":"image\/jpeg"}],"author":"desarrollo","twitter_card":"summary_large_image","twitter_creator":"@NASTICTARRAGONA","twitter_site":"@NASTICTARRAGONA","twitter_misc":{"Escrito por":"desarrollo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gimnasticdetarragona.cat\/es\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\/#article","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\/"},"author":{"name":"desarrollo","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e"},"headline":"\u00abTenemos que competir como nunca lo ha hecho el N\u00e0stic\u00bb RDP de Enrique Mart\u00edn","datePublished":"2018-11-23T17:51:48+00:00","mainEntityOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\/"},"wordCount":100,"commentCount":0,"publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/06001901141376.jpg","articleSection":["Actualidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gimnasticdetarragona.cat\/es\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\/","url":"https:\/\/gimnasticdetarragona.cat\/es\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\/","name":"\"Tenemos que competir como nunca lo ha hecho el N\u00e0stic\" RDP de Enrique Mart\u00edn - Gimn\u00e0stic de Tarragona SAD","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\/#primaryimage"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/06001901141376.jpg","datePublished":"2018-11-23T17:51:48+00:00","breadcrumb":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gimnasticdetarragona.cat\/es\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\/#primaryimage","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/06001901141376.jpg","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/06001901141376.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/gimnasticdetarragona.cat\/es\/hem-de-competir-com-no-ho-ha-fet-mai-el-nastic-rdp-denrique-martin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/gimnasticdetarragona.cat\/es\/nastic\/"},{"@type":"ListItem","position":2,"name":"\u00abTenemos que competir como nunca lo ha hecho el N\u00e0stic\u00bb RDP de Enrique Mart\u00edn"}]},{"@type":"WebSite","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website","url":"https:\/\/gimnasticdetarragona.cat\/es\/","name":"Gimn\u00e0stic de Tarragona SAD","description":"Gimn\u00e0stic de Tarragona","publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gimnasticdetarragona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization","name":"GIMN\u00c0STIC DE TARRAGONA","alternateName":"N\u00c0STIC","url":"https:\/\/gimnasticdetarragona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","width":224,"height":83,"caption":"GIMN\u00c0STIC DE TARRAGONA"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/NASTICTARRAGONA","https:\/\/www.instagram.com\/nastictarragona\/"]},{"@type":"Person","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e","name":"desarrollo","sameAs":["https:\/\/clone.gimnasticdetarragona.cat"]}]}},"_links":{"self":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/54973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/comments?post=54973"}],"version-history":[{"count":0,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/54973\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media\/54970"}],"wp:attachment":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media?parent=54973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/categories?post=54973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/tags?post=54973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}