{"id":55017,"date":"2018-11-19T16:37:12","date_gmt":"2018-11-19T16:37:12","guid":{"rendered":"https:\/\/clone.gimnasticdetarragona.cat\/una-entrada-per-soci-per-al-nastic-ud-almeria\/"},"modified":"2018-11-19T16:37:12","modified_gmt":"2018-11-19T16:37:12","slug":"una-entrada-per-soci-per-al-nastic-ud-almeria","status":"publish","type":"post","link":"https:\/\/gimnasticdetarragona.cat\/es\/una-entrada-per-soci-per-al-nastic-ud-almeria\/","title":{"rendered":"Una entrada por socio para el N\u00e0stic &#8211; UD Almer\u00eda"},"content":{"rendered":"<p style=\"text-align: justify;\">El entrenador del N\u00e0stic, Enrique Mart\u00edn, lanzaba el reto de ver una muy buena entrada en el Nou Estadi este s\u00e1bado a las 16 horas contra la UD Almer\u00eda. El t\u00e9cnico pide que la gente se ilusione, que no mire atr\u00e1s y que piense en el futuro y en ganar. Es un momento importante de la temporada y el apoyo de los aficionados es, sin duda, fundamental para conseguir las victorias.<\/p>\n<p style=\"text-align: justify;\">Por ello, se ofrece a todos los socios la posibilidad de retirar una entrada de la zona del campo donde est\u00e9n abonados, hasta agotar las localidades disponibles y as\u00ed poder invitar a ver el partido a alg\u00fan familiar o amigo.<\/p>\n<p style=\"text-align: justify;\">Recoge tu entrada:<\/p>\n<ul>\n<li style=\"text-align: justify;\">Oficinas de la SAD, de lunes a viernes de 9 a 13:30 horas y de 16 a 19 horas o s\u00e1bado desde dos horas antes del partit.<\/li>\n<li style=\"text-align: justify;\">Tienda y Museo de l&#8217;Av. Catalunya 22 C.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El N\u00e0stic ofrece a todos los socios la possibilidad de retirar una entrada de la zona del campo donde esten abonados, hasta agotar las localitades disponibles y as\u00ed poder invitar a ver el partido N\u00e0stic &#8211; UD Almer\u00eda a algun familiar o amigo.<\/p>\n","protected":false},"author":1,"featured_media":55014,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[113,126],"tags":[],"class_list":["post-55017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-primer-equipo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una entrada por socio para el N\u00e0stic - UD Almer\u00eda - Gimn\u00e0stic de Tarragona SAD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gimnasticdetarragona.cat\/es\/una-entrada-per-soci-per-al-nastic-ud-almeria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una entrada por socio para el N\u00e0stic - UD Almer\u00eda - Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"og:description\" content=\"El N\u00e0stic ofrece a todos los socios la possibilidad de retirar una entrada de la zona del campo donde esten abonados, hasta agotar las localitades disponibles y as\u00ed poder invitar a ver el partido N\u00e0stic - UD Almer\u00eda a algun familiar o amigo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gimnasticdetarragona.cat\/es\/una-entrada-per-soci-per-al-nastic-ud-almeria\/\" \/>\n<meta property=\"og:site_name\" content=\"Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-19T16:37:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/06001850140975.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"desarrollo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:site\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"desarrollo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/una-entrada-per-soci-per-al-nastic-ud-almeria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/una-entrada-per-soci-per-al-nastic-ud-almeria\\\/\"},\"author\":{\"name\":\"desarrollo\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\"},\"headline\":\"Una entrada por socio para el N\u00e0stic &#8211; UD Almer\u00eda\",\"datePublished\":\"2018-11-19T16:37:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/una-entrada-per-soci-per-al-nastic-ud-almeria\\\/\"},\"wordCount\":165,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/una-entrada-per-soci-per-al-nastic-ud-almeria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/06001850140975.jpg\",\"articleSection\":[\"Actualidad\",\"Primer Equipo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/una-entrada-per-soci-per-al-nastic-ud-almeria\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/una-entrada-per-soci-per-al-nastic-ud-almeria\\\/\",\"name\":\"Una entrada por socio para el N\u00e0stic - UD Almer\u00eda - Gimn\u00e0stic de Tarragona SAD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/una-entrada-per-soci-per-al-nastic-ud-almeria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/una-entrada-per-soci-per-al-nastic-ud-almeria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/06001850140975.jpg\",\"datePublished\":\"2018-11-19T16:37:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/una-entrada-per-soci-per-al-nastic-ud-almeria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/una-entrada-per-soci-per-al-nastic-ud-almeria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/una-entrada-per-soci-per-al-nastic-ud-almeria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/06001850140975.jpg\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/06001850140975.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/una-entrada-per-soci-per-al-nastic-ud-almeria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una entrada por socio para el N\u00e0stic &#8211; UD Almer\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"name\":\"Gimn\u00e0stic de Tarragona SAD\",\"description\":\"Gimn\u00e0stic de Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\",\"name\":\"GIMN\u00c0STIC DE TARRAGONA\",\"alternateName\":\"N\u00c0STIC\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"width\":224,\"height\":83,\"caption\":\"GIMN\u00c0STIC DE TARRAGONA\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/NASTICTARRAGONA\",\"https:\\\/\\\/www.instagram.com\\\/nastictarragona\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\",\"name\":\"desarrollo\",\"sameAs\":[\"https:\\\/\\\/clone.gimnasticdetarragona.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una entrada por socio para el N\u00e0stic - UD Almer\u00eda - Gimn\u00e0stic de Tarragona SAD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gimnasticdetarragona.cat\/es\/una-entrada-per-soci-per-al-nastic-ud-almeria\/","og_locale":"es_ES","og_type":"article","og_title":"Una entrada por socio para el N\u00e0stic - UD Almer\u00eda - Gimn\u00e0stic de Tarragona SAD","og_description":"El N\u00e0stic ofrece a todos los socios la possibilidad de retirar una entrada de la zona del campo donde esten abonados, hasta agotar las localitades disponibles y as\u00ed poder invitar a ver el partido N\u00e0stic - UD Almer\u00eda a algun familiar o amigo.","og_url":"https:\/\/gimnasticdetarragona.cat\/es\/una-entrada-per-soci-per-al-nastic-ud-almeria\/","og_site_name":"Gimn\u00e0stic de Tarragona SAD","article_published_time":"2018-11-19T16:37:12+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/06001850140975.jpg","type":"image\/jpeg"}],"author":"desarrollo","twitter_card":"summary_large_image","twitter_creator":"@NASTICTARRAGONA","twitter_site":"@NASTICTARRAGONA","twitter_misc":{"Escrito por":"desarrollo","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gimnasticdetarragona.cat\/es\/una-entrada-per-soci-per-al-nastic-ud-almeria\/#article","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/una-entrada-per-soci-per-al-nastic-ud-almeria\/"},"author":{"name":"desarrollo","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e"},"headline":"Una entrada por socio para el N\u00e0stic &#8211; UD Almer\u00eda","datePublished":"2018-11-19T16:37:12+00:00","mainEntityOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/una-entrada-per-soci-per-al-nastic-ud-almeria\/"},"wordCount":165,"commentCount":0,"publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/una-entrada-per-soci-per-al-nastic-ud-almeria\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/06001850140975.jpg","articleSection":["Actualidad","Primer Equipo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gimnasticdetarragona.cat\/es\/una-entrada-per-soci-per-al-nastic-ud-almeria\/","url":"https:\/\/gimnasticdetarragona.cat\/es\/una-entrada-per-soci-per-al-nastic-ud-almeria\/","name":"Una entrada por socio para el N\u00e0stic - UD Almer\u00eda - Gimn\u00e0stic de Tarragona SAD","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/una-entrada-per-soci-per-al-nastic-ud-almeria\/#primaryimage"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/una-entrada-per-soci-per-al-nastic-ud-almeria\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/06001850140975.jpg","datePublished":"2018-11-19T16:37:12+00:00","breadcrumb":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/una-entrada-per-soci-per-al-nastic-ud-almeria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gimnasticdetarragona.cat\/es\/una-entrada-per-soci-per-al-nastic-ud-almeria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/una-entrada-per-soci-per-al-nastic-ud-almeria\/#primaryimage","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/06001850140975.jpg","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/06001850140975.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/gimnasticdetarragona.cat\/es\/una-entrada-per-soci-per-al-nastic-ud-almeria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/gimnasticdetarragona.cat\/es\/nastic\/"},{"@type":"ListItem","position":2,"name":"Una entrada por socio para el N\u00e0stic &#8211; UD Almer\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website","url":"https:\/\/gimnasticdetarragona.cat\/es\/","name":"Gimn\u00e0stic de Tarragona SAD","description":"Gimn\u00e0stic de Tarragona","publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gimnasticdetarragona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization","name":"GIMN\u00c0STIC DE TARRAGONA","alternateName":"N\u00c0STIC","url":"https:\/\/gimnasticdetarragona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","width":224,"height":83,"caption":"GIMN\u00c0STIC DE TARRAGONA"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/NASTICTARRAGONA","https:\/\/www.instagram.com\/nastictarragona\/"]},{"@type":"Person","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e","name":"desarrollo","sameAs":["https:\/\/clone.gimnasticdetarragona.cat"]}]}},"_links":{"self":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/55017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/comments?post=55017"}],"version-history":[{"count":0,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/55017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media\/55014"}],"wp:attachment":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media?parent=55017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/categories?post=55017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/tags?post=55017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}