{"id":58427,"date":"2017-05-22T11:39:06","date_gmt":"2017-05-22T11:39:06","guid":{"rendered":"https:\/\/clone.gimnasticdetarragona.cat\/preferent-i-tribuna-esgotades-pel-nastic-girona\/"},"modified":"2017-05-22T11:39:06","modified_gmt":"2017-05-22T11:39:06","slug":"preferent-i-tribuna-esgotades-pel-nastic-girona","status":"publish","type":"post","link":"https:\/\/gimnasticdetarragona.cat\/es\/preferent-i-tribuna-esgotades-pel-nastic-girona\/","title":{"rendered":"Preferente y Tribuna, agotadas para el N\u00e0stic &#8211; Girona"},"content":{"rendered":"<p>El Gimn\u00e0stic de Tarragona, SAD informa que \u00fanicamente hay disponibles entradas a las zonas de Gol para el\u00a0partido del pr\u00f3ximo domingo 28 de mayo, a las 18 horas, en el Nou Estadi, entre el N\u00e0stic y el Girona FC.<\/p>\n<p>Recordamos que todos los socios, incluyendo los de Tribuna y Preferente, aun\u00a0tienen esta semana para retirar una entrada gratuita, de Gol Norte o Gol Sur. Esta promoci\u00f3n est\u00e1 limitada al n\u00famero de entradas disponibles, por el aforo, en cada una de las zonas del Nou Estadi.<\/p>\n<p>Por otra parte, recordamos la promoci\u00f3n para los socios y aficionados a la N\u00e0stic Hummel Store. La compra de una de las camisetas oficial del N\u00e0stic de esta temporada, al precio de 35 euros, significar\u00e1 una entrada gratis en la zona de Gol.<\/p>\n<p>El horario de las oficinas es de lunes a viernes, de 9 a 13.30 horas y de 16 a 19 horas, y el domingo 28 de mayo, d\u00eda de partido, se abrir\u00e1 a partir de las 16 horas. La N\u00e0stic Hummel Store tambi\u00e9n est\u00e1 abierta de lunes a viernes de 10 a 13.30 y de 17 a 20 horas, y tambi\u00e9n, el d\u00eda de partido, dos horas antes del inicio del encuentro ante el conjunto gerundense.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gimn\u00e0stic de Tarragona, SAD informa que \u00fanicamente hay disponibles entradas a las zonas de Gol para el partido del pr\u00f3ximo domingo 28 de mayo, a las 18 horas, en el Nou Estadi, entre el N\u00e0stic y el Girona FC.<\/p>\n","protected":false},"author":1,"featured_media":58424,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[113,121,126],"tags":[],"class_list":["post-58427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-home","category-primer-equipo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Preferente y Tribuna, agotadas para el N\u00e0stic - Girona - Gimn\u00e0stic de Tarragona SAD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gimnasticdetarragona.cat\/es\/preferent-i-tribuna-esgotades-pel-nastic-girona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Preferente y Tribuna, agotadas para el N\u00e0stic - Girona - Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"og:description\" content=\"El Gimn\u00e0stic de Tarragona, SAD informa que \u00fanicamente hay disponibles entradas a las zonas de Gol para el partido del pr\u00f3ximo domingo 28 de mayo, a las 18 horas, en el Nou Estadi, entre el N\u00e0stic y el Girona FC.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gimnasticdetarragona.cat\/es\/preferent-i-tribuna-esgotades-pel-nastic-girona\/\" \/>\n<meta property=\"og:site_name\" content=\"Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-22T11:39:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05235559121687.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"desarrollo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:site\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"desarrollo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/preferent-i-tribuna-esgotades-pel-nastic-girona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/preferent-i-tribuna-esgotades-pel-nastic-girona\\\/\"},\"author\":{\"name\":\"desarrollo\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\"},\"headline\":\"Preferente y Tribuna, agotadas para el N\u00e0stic &#8211; Girona\",\"datePublished\":\"2017-05-22T11:39:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/preferent-i-tribuna-esgotades-pel-nastic-girona\\\/\"},\"wordCount\":216,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/preferent-i-tribuna-esgotades-pel-nastic-girona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/05235559121687.jpg\",\"articleSection\":[\"Actualidad\",\"Home\",\"Primer Equipo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/preferent-i-tribuna-esgotades-pel-nastic-girona\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/preferent-i-tribuna-esgotades-pel-nastic-girona\\\/\",\"name\":\"Preferente y Tribuna, agotadas para el N\u00e0stic - Girona - Gimn\u00e0stic de Tarragona SAD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/preferent-i-tribuna-esgotades-pel-nastic-girona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/preferent-i-tribuna-esgotades-pel-nastic-girona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/05235559121687.jpg\",\"datePublished\":\"2017-05-22T11:39:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/preferent-i-tribuna-esgotades-pel-nastic-girona\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/preferent-i-tribuna-esgotades-pel-nastic-girona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/preferent-i-tribuna-esgotades-pel-nastic-girona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/05235559121687.jpg\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/05235559121687.jpg\",\"width\":1200,\"height\":627},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/preferent-i-tribuna-esgotades-pel-nastic-girona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Preferente y Tribuna, agotadas para el N\u00e0stic &#8211; Girona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"name\":\"Gimn\u00e0stic de Tarragona SAD\",\"description\":\"Gimn\u00e0stic de Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\",\"name\":\"GIMN\u00c0STIC DE TARRAGONA\",\"alternateName\":\"N\u00c0STIC\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"width\":224,\"height\":83,\"caption\":\"GIMN\u00c0STIC DE TARRAGONA\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/NASTICTARRAGONA\",\"https:\\\/\\\/www.instagram.com\\\/nastictarragona\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\",\"name\":\"desarrollo\",\"sameAs\":[\"https:\\\/\\\/clone.gimnasticdetarragona.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Preferente y Tribuna, agotadas para el N\u00e0stic - Girona - Gimn\u00e0stic de Tarragona SAD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gimnasticdetarragona.cat\/es\/preferent-i-tribuna-esgotades-pel-nastic-girona\/","og_locale":"es_ES","og_type":"article","og_title":"Preferente y Tribuna, agotadas para el N\u00e0stic - Girona - Gimn\u00e0stic de Tarragona SAD","og_description":"El Gimn\u00e0stic de Tarragona, SAD informa que \u00fanicamente hay disponibles entradas a las zonas de Gol para el partido del pr\u00f3ximo domingo 28 de mayo, a las 18 horas, en el Nou Estadi, entre el N\u00e0stic y el Girona FC.","og_url":"https:\/\/gimnasticdetarragona.cat\/es\/preferent-i-tribuna-esgotades-pel-nastic-girona\/","og_site_name":"Gimn\u00e0stic de Tarragona SAD","article_published_time":"2017-05-22T11:39:06+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05235559121687.jpg","type":"image\/jpeg"}],"author":"desarrollo","twitter_card":"summary_large_image","twitter_creator":"@NASTICTARRAGONA","twitter_site":"@NASTICTARRAGONA","twitter_misc":{"Escrito por":"desarrollo","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gimnasticdetarragona.cat\/es\/preferent-i-tribuna-esgotades-pel-nastic-girona\/#article","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/preferent-i-tribuna-esgotades-pel-nastic-girona\/"},"author":{"name":"desarrollo","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e"},"headline":"Preferente y Tribuna, agotadas para el N\u00e0stic &#8211; Girona","datePublished":"2017-05-22T11:39:06+00:00","mainEntityOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/preferent-i-tribuna-esgotades-pel-nastic-girona\/"},"wordCount":216,"commentCount":0,"publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/preferent-i-tribuna-esgotades-pel-nastic-girona\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05235559121687.jpg","articleSection":["Actualidad","Home","Primer Equipo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gimnasticdetarragona.cat\/es\/preferent-i-tribuna-esgotades-pel-nastic-girona\/","url":"https:\/\/gimnasticdetarragona.cat\/es\/preferent-i-tribuna-esgotades-pel-nastic-girona\/","name":"Preferente y Tribuna, agotadas para el N\u00e0stic - Girona - Gimn\u00e0stic de Tarragona SAD","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/preferent-i-tribuna-esgotades-pel-nastic-girona\/#primaryimage"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/preferent-i-tribuna-esgotades-pel-nastic-girona\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05235559121687.jpg","datePublished":"2017-05-22T11:39:06+00:00","breadcrumb":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/preferent-i-tribuna-esgotades-pel-nastic-girona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gimnasticdetarragona.cat\/es\/preferent-i-tribuna-esgotades-pel-nastic-girona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/preferent-i-tribuna-esgotades-pel-nastic-girona\/#primaryimage","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05235559121687.jpg","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05235559121687.jpg","width":1200,"height":627},{"@type":"BreadcrumbList","@id":"https:\/\/gimnasticdetarragona.cat\/es\/preferent-i-tribuna-esgotades-pel-nastic-girona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/gimnasticdetarragona.cat\/es\/nastic\/"},{"@type":"ListItem","position":2,"name":"Preferente y Tribuna, agotadas para el N\u00e0stic &#8211; Girona"}]},{"@type":"WebSite","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website","url":"https:\/\/gimnasticdetarragona.cat\/es\/","name":"Gimn\u00e0stic de Tarragona SAD","description":"Gimn\u00e0stic de Tarragona","publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gimnasticdetarragona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization","name":"GIMN\u00c0STIC DE TARRAGONA","alternateName":"N\u00c0STIC","url":"https:\/\/gimnasticdetarragona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","width":224,"height":83,"caption":"GIMN\u00c0STIC DE TARRAGONA"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/NASTICTARRAGONA","https:\/\/www.instagram.com\/nastictarragona\/"]},{"@type":"Person","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e","name":"desarrollo","sameAs":["https:\/\/clone.gimnasticdetarragona.cat"]}]}},"_links":{"self":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/58427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/comments?post=58427"}],"version-history":[{"count":0,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/58427\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media\/58424"}],"wp:attachment":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media?parent=58427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/categories?post=58427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/tags?post=58427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}