{"id":59356,"date":"2017-02-15T16:53:42","date_gmt":"2017-02-15T16:53:42","guid":{"rendered":"https:\/\/clone.gimnasticdetarragona.cat\/pelota-pleno-de-victorias-de-la-seccion-grana\/"},"modified":"2017-02-15T16:53:42","modified_gmt":"2017-02-15T16:53:42","slug":"pelota-pleno-de-victorias-de-la-seccion-grana","status":"publish","type":"post","link":"https:\/\/gimnasticdetarragona.cat\/es\/pelota-pleno-de-victorias-de-la-seccion-grana\/","title":{"rendered":"Pelota | Pleno de victorias de la secci\u00f3n grana"},"content":{"rendered":"<p style=\"text-align: justify;\">Por cuarta jornada consecutiva el N&agrave;stic se impone en la liga del Campeonato de Catalu&ntilde;a de Pelota Preol&iacute;mpica, de tercera categor&iacute;a, y es l&iacute;der de la clasificaci&oacute;n. La pareja grana se llev&oacute; el triunfo ante el CN Terrassa &#8216;A&#8217;.<\/p>\n<p style=\"text-align: justify;\">La pareja nastiquera habitual, formada por Juan Jos&eacute; Perroni y Jes&uacute;s Dom&iacute;nguez, se llevaba la partida por dos sets a cero ante la dupla visitante, Sandra Rodr&iacute;guez y Nelson Cusco. Los parciales finales de los dos sets fueron de 15 a 6 y 15 a 5, mostrando la solidez de los pelotaris del Club Gimn&agrave;stic. Perroni y Dom&iacute;nguez, que cuentan los partidos por victorias y se sit&uacute;an a la cabeza del campeonato catal&aacute;n.<\/p>\n<p style=\"text-align: justify;\">Cabe destacar que la jugadora Sandra Rodr&iacute;guez, del CN Terrassa, ha sido la primera chica que ha jugado en competici&oacute;n oficial en la pista de front&oacute;n del Club Gimn&agrave;stic de Tarragona.<\/p>\n<p style=\"text-align: justify;\">Antes de la disputa del encuentro, se guard&oacute; un respetuoso minuto de silencio por la p&eacute;rdida de Marbel Negueruela, concejala de Deportes del Ajuntament&nbsp;de Tarragona.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por cuarta jornada consecutiva el N\u00e0stic se impone en la liga del Campeonato de Catalu\u00f1a de Pelota Preol\u00edmpica, de tercera categor\u00eda, y es l\u00edder de la clasificaci\u00f3n. La pareja grana se llev\u00f3 el triunfo ante el CN Terrassa &#8216;A&#8217;.<\/p>\n","protected":false},"author":1,"featured_media":59353,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[113,121,135,127],"tags":[],"class_list":["post-59356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-home","category-pelota","category-secciones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pelota | Pleno de victorias de la secci\u00f3n grana - Gimn\u00e0stic de Tarragona SAD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gimnasticdetarragona.cat\/es\/pelota-pleno-de-victorias-de-la-seccion-grana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pelota | Pleno de victorias de la secci\u00f3n grana - Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"og:description\" content=\"Por cuarta jornada consecutiva el N\u00e0stic se impone en la liga del Campeonato de Catalu\u00f1a de Pelota Preol\u00edmpica, de tercera categor\u00eda, y es l\u00edder de la clasificaci\u00f3n. La pareja grana se llev\u00f3 el triunfo ante el CN Terrassa &#039;A&#039;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gimnasticdetarragona.cat\/es\/pelota-pleno-de-victorias-de-la-seccion-grana\/\" \/>\n<meta property=\"og:site_name\" content=\"Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-15T16:53:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05235031118534.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"835\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"desarrollo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:site\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"desarrollo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pelota-pleno-de-victorias-de-la-seccion-grana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pelota-pleno-de-victorias-de-la-seccion-grana\\\/\"},\"author\":{\"name\":\"desarrollo\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\"},\"headline\":\"Pelota | Pleno de victorias de la secci\u00f3n grana\",\"datePublished\":\"2017-02-15T16:53:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pelota-pleno-de-victorias-de-la-seccion-grana\\\/\"},\"wordCount\":214,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pelota-pleno-de-victorias-de-la-seccion-grana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/05235031118534.jpg\",\"articleSection\":[\"Actualidad\",\"Home\",\"Secci\u00f3n Pelota\",\"Secciones\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pelota-pleno-de-victorias-de-la-seccion-grana\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pelota-pleno-de-victorias-de-la-seccion-grana\\\/\",\"name\":\"Pelota | Pleno de victorias de la secci\u00f3n grana - Gimn\u00e0stic de Tarragona SAD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pelota-pleno-de-victorias-de-la-seccion-grana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pelota-pleno-de-victorias-de-la-seccion-grana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/05235031118534.jpg\",\"datePublished\":\"2017-02-15T16:53:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pelota-pleno-de-victorias-de-la-seccion-grana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pelota-pleno-de-victorias-de-la-seccion-grana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pelota-pleno-de-victorias-de-la-seccion-grana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/05235031118534.jpg\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/05235031118534.jpg\",\"width\":1400,\"height\":835},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pelota-pleno-de-victorias-de-la-seccion-grana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pelota | Pleno de victorias de la secci\u00f3n grana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"name\":\"Gimn\u00e0stic de Tarragona SAD\",\"description\":\"Gimn\u00e0stic de Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\",\"name\":\"GIMN\u00c0STIC DE TARRAGONA\",\"alternateName\":\"N\u00c0STIC\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"width\":224,\"height\":83,\"caption\":\"GIMN\u00c0STIC DE TARRAGONA\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/NASTICTARRAGONA\",\"https:\\\/\\\/www.instagram.com\\\/nastictarragona\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\",\"name\":\"desarrollo\",\"sameAs\":[\"https:\\\/\\\/clone.gimnasticdetarragona.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pelota | Pleno de victorias de la secci\u00f3n grana - Gimn\u00e0stic de Tarragona SAD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gimnasticdetarragona.cat\/es\/pelota-pleno-de-victorias-de-la-seccion-grana\/","og_locale":"es_ES","og_type":"article","og_title":"Pelota | Pleno de victorias de la secci\u00f3n grana - Gimn\u00e0stic de Tarragona SAD","og_description":"Por cuarta jornada consecutiva el N\u00e0stic se impone en la liga del Campeonato de Catalu\u00f1a de Pelota Preol\u00edmpica, de tercera categor\u00eda, y es l\u00edder de la clasificaci\u00f3n. La pareja grana se llev\u00f3 el triunfo ante el CN Terrassa 'A'.","og_url":"https:\/\/gimnasticdetarragona.cat\/es\/pelota-pleno-de-victorias-de-la-seccion-grana\/","og_site_name":"Gimn\u00e0stic de Tarragona SAD","article_published_time":"2017-02-15T16:53:42+00:00","og_image":[{"width":1400,"height":835,"url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05235031118534.jpg","type":"image\/jpeg"}],"author":"desarrollo","twitter_card":"summary_large_image","twitter_creator":"@NASTICTARRAGONA","twitter_site":"@NASTICTARRAGONA","twitter_misc":{"Escrito por":"desarrollo","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gimnasticdetarragona.cat\/es\/pelota-pleno-de-victorias-de-la-seccion-grana\/#article","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/pelota-pleno-de-victorias-de-la-seccion-grana\/"},"author":{"name":"desarrollo","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e"},"headline":"Pelota | Pleno de victorias de la secci\u00f3n grana","datePublished":"2017-02-15T16:53:42+00:00","mainEntityOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/pelota-pleno-de-victorias-de-la-seccion-grana\/"},"wordCount":214,"commentCount":0,"publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/pelota-pleno-de-victorias-de-la-seccion-grana\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05235031118534.jpg","articleSection":["Actualidad","Home","Secci\u00f3n Pelota","Secciones"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gimnasticdetarragona.cat\/es\/pelota-pleno-de-victorias-de-la-seccion-grana\/","url":"https:\/\/gimnasticdetarragona.cat\/es\/pelota-pleno-de-victorias-de-la-seccion-grana\/","name":"Pelota | Pleno de victorias de la secci\u00f3n grana - Gimn\u00e0stic de Tarragona SAD","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/pelota-pleno-de-victorias-de-la-seccion-grana\/#primaryimage"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/pelota-pleno-de-victorias-de-la-seccion-grana\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05235031118534.jpg","datePublished":"2017-02-15T16:53:42+00:00","breadcrumb":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/pelota-pleno-de-victorias-de-la-seccion-grana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gimnasticdetarragona.cat\/es\/pelota-pleno-de-victorias-de-la-seccion-grana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/pelota-pleno-de-victorias-de-la-seccion-grana\/#primaryimage","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05235031118534.jpg","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05235031118534.jpg","width":1400,"height":835},{"@type":"BreadcrumbList","@id":"https:\/\/gimnasticdetarragona.cat\/es\/pelota-pleno-de-victorias-de-la-seccion-grana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/gimnasticdetarragona.cat\/es\/nastic\/"},{"@type":"ListItem","position":2,"name":"Pelota | Pleno de victorias de la secci\u00f3n grana"}]},{"@type":"WebSite","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website","url":"https:\/\/gimnasticdetarragona.cat\/es\/","name":"Gimn\u00e0stic de Tarragona SAD","description":"Gimn\u00e0stic de Tarragona","publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gimnasticdetarragona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization","name":"GIMN\u00c0STIC DE TARRAGONA","alternateName":"N\u00c0STIC","url":"https:\/\/gimnasticdetarragona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","width":224,"height":83,"caption":"GIMN\u00c0STIC DE TARRAGONA"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/NASTICTARRAGONA","https:\/\/www.instagram.com\/nastictarragona\/"]},{"@type":"Person","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e","name":"desarrollo","sameAs":["https:\/\/clone.gimnasticdetarragona.cat"]}]}},"_links":{"self":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/59356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/comments?post=59356"}],"version-history":[{"count":0,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/59356\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media\/59353"}],"wp:attachment":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media?parent=59356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/categories?post=59356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/tags?post=59356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}