{"id":59384,"date":"2017-02-13T13:03:24","date_gmt":"2017-02-13T13:03:24","guid":{"rendered":"https:\/\/clone.gimnasticdetarragona.cat\/un-buen-juvenil-a\/"},"modified":"2017-02-13T13:03:24","modified_gmt":"2017-02-13T13:03:24","slug":"un-buen-juvenil-a","status":"publish","type":"post","link":"https:\/\/gimnasticdetarragona.cat\/es\/un-buen-juvenil-a\/","title":{"rendered":"Un buen Juvenil A planta cara al Cornell\u00e0"},"content":{"rendered":"<p style=\"text-align: justify;\">Los de Manel Cazorla perdieron en el campo del tercer clasificado, el Cornell\u00e0, despu\u00e9s de ver como los locales remontaban el tanto inicial de Verdejo.<\/p>\n<p style=\"text-align: justify;\">Los grana comenzaron muy finos el partido, dominando y disfrutando de buenas llegadas. En el minuto 22 los tarraconenses se pon\u00edan por delante en el marcador y antes del descanso a\u00fan disfrutar\u00edan de dos ocasiones muy claras para ampliar la ventaja. En la media parte se lleg\u00f3 con el 0-1.<\/p>\n<p style=\"text-align: justify;\">La segunda mitad mantuvo el gui\u00f3n inicial, con un N\u00e0stic dominador y mostr\u00e1ndose muy s\u00f3lido en todos los registros del juego. Los de Cazorla volvieron a disfrutar de hasta tres ocasiones claras pero no fueron capaces de sentenciar. Por el contrario, con el paso de los minutos los del Llobregat comenzaron a apoderarse de la pelota, y en 10 minutos muy buenos, fueron capaces de darle la vuelta al marcador. Con el 2 a 1 los grana a\u00fan tuvieron opciones, e incluso fallaron un penalti, pero finalmente fueron de nuevo los locales los que marcaron consiguiendo el definitivo 3 a 1.<\/p>\n<p style=\"text-align: justify;\">El t\u00e9cnico del Juvenil A, Manuel Cazorla, destacaba al final del partido el gran trabajo de sus jugadores. \u00abHemos dominado al tercer clasificado durante m\u00e1s de 60 minutos. Hubi\u00e9ramos podido hacer el 0-2 pero no hemos tenido fortuna y al final ellos han demostrado que no es casualidad su clasificaci\u00f3n. Son un gran equipo, est\u00e1n en una din\u00e1mica muy buena y, a\u00fan as\u00ed, fuimos los protagonistas durante gran parte del encuentro. Estamos jugando muy bien, tenemos que mantener la convicci\u00f3n en el trabajo que estamos haciendo y seguir luchando. Ahora nos visita otro gran equipo como es La Damm pero estoy seguro de que si rendimos al nivel de este fin de semana seremos capaces de hacer que los tres puntos se queden en Tarragona \u00ab.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los de Manel Cazorla perdieron en el campo del tercer clasificado, el Cornell\u00e0, despu\u00e9s de ver como los locales remontaban el tanto inicial de Verdejo.<\/p>\n","protected":false},"author":1,"featured_media":59381,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[113,117],"tags":[],"class_list":["post-59384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-futbol-base"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un buen Juvenil A planta cara al Cornell\u00e0 - Gimn\u00e0stic de Tarragona SAD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gimnasticdetarragona.cat\/es\/un-buen-juvenil-a\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un buen Juvenil A planta cara al Cornell\u00e0 - Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"og:description\" content=\"Los de Manel Cazorla perdieron en el campo del tercer clasificado, el Cornell\u00e0, despu\u00e9s de ver como los locales remontaban el tanto inicial de Verdejo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gimnasticdetarragona.cat\/es\/un-buen-juvenil-a\/\" \/>\n<meta property=\"og:site_name\" content=\"Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-13T13:03:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05235027118453.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"330\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"desarrollo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:site\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"desarrollo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/un-buen-juvenil-a\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/un-buen-juvenil-a\\\/\"},\"author\":{\"name\":\"desarrollo\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\"},\"headline\":\"Un buen Juvenil A planta cara al Cornell\u00e0\",\"datePublished\":\"2017-02-13T13:03:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/un-buen-juvenil-a\\\/\"},\"wordCount\":319,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/un-buen-juvenil-a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/05235027118453.jpg\",\"articleSection\":[\"Actualidad\",\"F\u00fatbol Base\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/un-buen-juvenil-a\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/un-buen-juvenil-a\\\/\",\"name\":\"Un buen Juvenil A planta cara al Cornell\u00e0 - Gimn\u00e0stic de Tarragona SAD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/un-buen-juvenil-a\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/un-buen-juvenil-a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/05235027118453.jpg\",\"datePublished\":\"2017-02-13T13:03:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/un-buen-juvenil-a\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/un-buen-juvenil-a\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/un-buen-juvenil-a\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/05235027118453.jpg\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/05235027118453.jpg\",\"width\":660,\"height\":330},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/un-buen-juvenil-a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un buen Juvenil A planta cara al Cornell\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"name\":\"Gimn\u00e0stic de Tarragona SAD\",\"description\":\"Gimn\u00e0stic de Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\",\"name\":\"GIMN\u00c0STIC DE TARRAGONA\",\"alternateName\":\"N\u00c0STIC\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"width\":224,\"height\":83,\"caption\":\"GIMN\u00c0STIC DE TARRAGONA\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/NASTICTARRAGONA\",\"https:\\\/\\\/www.instagram.com\\\/nastictarragona\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\",\"name\":\"desarrollo\",\"sameAs\":[\"https:\\\/\\\/clone.gimnasticdetarragona.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un buen Juvenil A planta cara al Cornell\u00e0 - Gimn\u00e0stic de Tarragona SAD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gimnasticdetarragona.cat\/es\/un-buen-juvenil-a\/","og_locale":"es_ES","og_type":"article","og_title":"Un buen Juvenil A planta cara al Cornell\u00e0 - Gimn\u00e0stic de Tarragona SAD","og_description":"Los de Manel Cazorla perdieron en el campo del tercer clasificado, el Cornell\u00e0, despu\u00e9s de ver como los locales remontaban el tanto inicial de Verdejo.","og_url":"https:\/\/gimnasticdetarragona.cat\/es\/un-buen-juvenil-a\/","og_site_name":"Gimn\u00e0stic de Tarragona SAD","article_published_time":"2017-02-13T13:03:24+00:00","og_image":[{"width":660,"height":330,"url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05235027118453.jpg","type":"image\/jpeg"}],"author":"desarrollo","twitter_card":"summary_large_image","twitter_creator":"@NASTICTARRAGONA","twitter_site":"@NASTICTARRAGONA","twitter_misc":{"Escrito por":"desarrollo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gimnasticdetarragona.cat\/es\/un-buen-juvenil-a\/#article","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/un-buen-juvenil-a\/"},"author":{"name":"desarrollo","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e"},"headline":"Un buen Juvenil A planta cara al Cornell\u00e0","datePublished":"2017-02-13T13:03:24+00:00","mainEntityOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/un-buen-juvenil-a\/"},"wordCount":319,"commentCount":0,"publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/un-buen-juvenil-a\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05235027118453.jpg","articleSection":["Actualidad","F\u00fatbol Base"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gimnasticdetarragona.cat\/es\/un-buen-juvenil-a\/","url":"https:\/\/gimnasticdetarragona.cat\/es\/un-buen-juvenil-a\/","name":"Un buen Juvenil A planta cara al Cornell\u00e0 - Gimn\u00e0stic de Tarragona SAD","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/un-buen-juvenil-a\/#primaryimage"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/un-buen-juvenil-a\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05235027118453.jpg","datePublished":"2017-02-13T13:03:24+00:00","breadcrumb":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/un-buen-juvenil-a\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gimnasticdetarragona.cat\/es\/un-buen-juvenil-a\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/un-buen-juvenil-a\/#primaryimage","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05235027118453.jpg","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05235027118453.jpg","width":660,"height":330},{"@type":"BreadcrumbList","@id":"https:\/\/gimnasticdetarragona.cat\/es\/un-buen-juvenil-a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/gimnasticdetarragona.cat\/es\/nastic\/"},{"@type":"ListItem","position":2,"name":"Un buen Juvenil A planta cara al Cornell\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website","url":"https:\/\/gimnasticdetarragona.cat\/es\/","name":"Gimn\u00e0stic de Tarragona SAD","description":"Gimn\u00e0stic de Tarragona","publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gimnasticdetarragona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization","name":"GIMN\u00c0STIC DE TARRAGONA","alternateName":"N\u00c0STIC","url":"https:\/\/gimnasticdetarragona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","width":224,"height":83,"caption":"GIMN\u00c0STIC DE TARRAGONA"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/NASTICTARRAGONA","https:\/\/www.instagram.com\/nastictarragona\/"]},{"@type":"Person","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e","name":"desarrollo","sameAs":["https:\/\/clone.gimnasticdetarragona.cat"]}]}},"_links":{"self":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/59384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/comments?post=59384"}],"version-history":[{"count":0,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/59384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media\/59381"}],"wp:attachment":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media?parent=59384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/categories?post=59384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/tags?post=59384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}