{"id":60295,"date":"2016-11-04T18:01:44","date_gmt":"2016-11-04T18:01:44","guid":{"rendered":"https:\/\/clone.gimnasticdetarragona.cat\/partits-destacats-de-la-pedreragrana\/"},"modified":"2016-11-04T18:01:44","modified_gmt":"2016-11-04T18:01:44","slug":"partits-destacats-de-la-pedreragrana","status":"publish","type":"post","link":"https:\/\/gimnasticdetarragona.cat\/es\/partits-destacats-de-la-pedreragrana\/","title":{"rendered":"Partidos destacados del #PlanterGrana"},"content":{"rendered":"<p style=\"text-align: justify;\">Partidos destacados del #PlanterGrana de este fin de semana.<\/p>\n<p style=\"text-align: justify;\">Cadete A<\/p>\n<p style=\"text-align: justify;\">Los de Bruno Uria juegan contra el Lleida Esportiu, equipo situado en la parte baja, as\u00ed que ser\u00e1 una buena oportunidad para intentar sacar 3 puntos tras el \u00faltimo y espectacular partido en casa contra el Jabac que acab\u00f3 con empate a 4.<\/p>\n<p style=\"text-align: justify;\">Infantil A<\/p>\n<p style=\"text-align: justify;\">Los de Paco Pastor reciben al Sabadell, en un partido en que intentar\u00e1n sumar la 2\u00aa victoria seguida como locales ante un equipo nuevo en la categor\u00eda al igual que los grana. Es un partido importante para empezar a escalar posiciones.<\/p>\n<p style=\"text-align: justify;\">Infantil F<\/p>\n<p style=\"text-align: justify;\">Los chicos de Alberto Fern\u00e1ndez, intentar\u00e1n ganar su 3er partido consecutivo ante el Sta. Oliva y reafirmar as\u00ed el gran inicio de temporada de los grana. Hay que recordar que se trata de un conjunto formado \u00edntegramente por jugadores de 1\u00ba a\u00f1o por los que es, por tanto, la primera temporada en F11.<\/p>\n<p style=\"text-align: justify;\">Prebenjam\u00edn C<\/p>\n<p style=\"text-align: justify;\">Los prebenjamines juegan ante la Canonja A, el s\u00e1bado por la ma\u00f1ana, e intentar\u00e1n mantenerse invictos, ganando el que ser\u00eda el sexto partido consecutivo.<\/p>\n<p style=\"text-align: justify;\">Alev\u00edn A<\/p>\n<p style=\"text-align: justify;\">El equipo de Pol Garcia juega ante la Floresta en su campo. Un derby como este es siempre un partido muy intenso en que los de Ponent pondr\u00e1n, a buen seguro, las cosas muy dif\u00edciles para sacar los 3 puntos. El alev\u00edn intentar\u00e1, con su buena progresi\u00f3n y adaptaci\u00f3n a la categor\u00eda, seguir luchando por los puestos de cabeza.<\/p>\n<p style=\"text-align: justify;\">Benjam\u00edn A<\/p>\n<p style=\"text-align: justify;\">Los de Jordi Martin juegan el domingo como locales el derbi por antonomasia; a priori el Reus es favorito ya que cuenta con un grupo m\u00e1s conjuntado pero seguro que nuestros peque\u00f1os presentar\u00e1n batalla y competir\u00e1n el partido. Los tarraconenses intentar\u00e1n hacer perder los primeros puntos de la temporada a los ganxets.<\/p>\n<p style=\"text-align: justify;\">Prebenjam\u00edn F<\/p>\n<p style=\"text-align: justify;\">Despu\u00e9s de saborear la 1\u00aa victoria de la temporada, los peque\u00f1os de Alex Ca\u00f1as visitan Roda de Bar\u00e0 con las pilas cargadas para intentar volver a hacer un gran papel.<\/p>\n<p style=\"text-align: justify;\">Benjam\u00edn C<\/p>\n<p style=\"text-align: justify;\">Los benjamines juegan el s\u00e1bado en Reus vs Mas Pellicer donde, despu\u00e9s de un inicio dubitativo, intentar\u00e1n seguir creciendo logrando otra victoria. Los chicos de Sergi Diaz luchar\u00e1n por conseguirla.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resum dels partits m\u00e9s destacats del #PlanterGrana d&#8217;aquest cap de semana.<\/p>\n","protected":false},"author":1,"featured_media":60292,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[113,117],"tags":[],"class_list":["post-60295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-futbol-base"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Partidos destacados del #PlanterGrana - Gimn\u00e0stic de Tarragona SAD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gimnasticdetarragona.cat\/es\/partits-destacats-de-la-pedreragrana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Partidos destacados del #PlanterGrana - Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"og:description\" content=\"Resum dels partits m\u00e9s destacats del #PlanterGrana d&#039;aquest cap de semana.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gimnasticdetarragona.cat\/es\/partits-destacats-de-la-pedreragrana\/\" \/>\n<meta property=\"og:site_name\" content=\"Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-04T18:01:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05234322114834.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"desarrollo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:site\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"desarrollo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/partits-destacats-de-la-pedreragrana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/partits-destacats-de-la-pedreragrana\\\/\"},\"author\":{\"name\":\"desarrollo\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\"},\"headline\":\"Partidos destacados del #PlanterGrana\",\"datePublished\":\"2016-11-04T18:01:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/partits-destacats-de-la-pedreragrana\\\/\"},\"wordCount\":387,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/partits-destacats-de-la-pedreragrana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/05234322114834.jpg\",\"articleSection\":[\"Actualidad\",\"F\u00fatbol Base\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/partits-destacats-de-la-pedreragrana\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/partits-destacats-de-la-pedreragrana\\\/\",\"name\":\"Partidos destacados del #PlanterGrana - Gimn\u00e0stic de Tarragona SAD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/partits-destacats-de-la-pedreragrana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/partits-destacats-de-la-pedreragrana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/05234322114834.jpg\",\"datePublished\":\"2016-11-04T18:01:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/partits-destacats-de-la-pedreragrana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/partits-destacats-de-la-pedreragrana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/partits-destacats-de-la-pedreragrana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/05234322114834.jpg\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/05234322114834.jpg\",\"width\":600,\"height\":400,\"caption\":\"????????????????????????????????????\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/partits-destacats-de-la-pedreragrana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Partidos destacados del #PlanterGrana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"name\":\"Gimn\u00e0stic de Tarragona SAD\",\"description\":\"Gimn\u00e0stic de Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\",\"name\":\"GIMN\u00c0STIC DE TARRAGONA\",\"alternateName\":\"N\u00c0STIC\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"width\":224,\"height\":83,\"caption\":\"GIMN\u00c0STIC DE TARRAGONA\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/NASTICTARRAGONA\",\"https:\\\/\\\/www.instagram.com\\\/nastictarragona\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\",\"name\":\"desarrollo\",\"sameAs\":[\"https:\\\/\\\/clone.gimnasticdetarragona.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Partidos destacados del #PlanterGrana - Gimn\u00e0stic de Tarragona SAD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gimnasticdetarragona.cat\/es\/partits-destacats-de-la-pedreragrana\/","og_locale":"es_ES","og_type":"article","og_title":"Partidos destacados del #PlanterGrana - Gimn\u00e0stic de Tarragona SAD","og_description":"Resum dels partits m\u00e9s destacats del #PlanterGrana d'aquest cap de semana.","og_url":"https:\/\/gimnasticdetarragona.cat\/es\/partits-destacats-de-la-pedreragrana\/","og_site_name":"Gimn\u00e0stic de Tarragona SAD","article_published_time":"2016-11-04T18:01:44+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05234322114834.jpg","type":"image\/jpeg"}],"author":"desarrollo","twitter_card":"summary_large_image","twitter_creator":"@NASTICTARRAGONA","twitter_site":"@NASTICTARRAGONA","twitter_misc":{"Escrito por":"desarrollo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gimnasticdetarragona.cat\/es\/partits-destacats-de-la-pedreragrana\/#article","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/partits-destacats-de-la-pedreragrana\/"},"author":{"name":"desarrollo","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e"},"headline":"Partidos destacados del #PlanterGrana","datePublished":"2016-11-04T18:01:44+00:00","mainEntityOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/partits-destacats-de-la-pedreragrana\/"},"wordCount":387,"commentCount":0,"publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/partits-destacats-de-la-pedreragrana\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05234322114834.jpg","articleSection":["Actualidad","F\u00fatbol Base"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gimnasticdetarragona.cat\/es\/partits-destacats-de-la-pedreragrana\/","url":"https:\/\/gimnasticdetarragona.cat\/es\/partits-destacats-de-la-pedreragrana\/","name":"Partidos destacados del #PlanterGrana - Gimn\u00e0stic de Tarragona SAD","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/partits-destacats-de-la-pedreragrana\/#primaryimage"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/partits-destacats-de-la-pedreragrana\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05234322114834.jpg","datePublished":"2016-11-04T18:01:44+00:00","breadcrumb":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/partits-destacats-de-la-pedreragrana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gimnasticdetarragona.cat\/es\/partits-destacats-de-la-pedreragrana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/partits-destacats-de-la-pedreragrana\/#primaryimage","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05234322114834.jpg","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05234322114834.jpg","width":600,"height":400,"caption":"????????????????????????????????????"},{"@type":"BreadcrumbList","@id":"https:\/\/gimnasticdetarragona.cat\/es\/partits-destacats-de-la-pedreragrana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/gimnasticdetarragona.cat\/es\/nastic\/"},{"@type":"ListItem","position":2,"name":"Partidos destacados del #PlanterGrana"}]},{"@type":"WebSite","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website","url":"https:\/\/gimnasticdetarragona.cat\/es\/","name":"Gimn\u00e0stic de Tarragona SAD","description":"Gimn\u00e0stic de Tarragona","publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gimnasticdetarragona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization","name":"GIMN\u00c0STIC DE TARRAGONA","alternateName":"N\u00c0STIC","url":"https:\/\/gimnasticdetarragona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","width":224,"height":83,"caption":"GIMN\u00c0STIC DE TARRAGONA"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/NASTICTARRAGONA","https:\/\/www.instagram.com\/nastictarragona\/"]},{"@type":"Person","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e","name":"desarrollo","sameAs":["https:\/\/clone.gimnasticdetarragona.cat"]}]}},"_links":{"self":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/60295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/comments?post=60295"}],"version-history":[{"count":0,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/60295\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media\/60292"}],"wp:attachment":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media?parent=60295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/categories?post=60295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/tags?post=60295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}