{"id":60615,"date":"2016-09-28T19:23:18","date_gmt":"2016-09-28T19:23:18","guid":{"rendered":"https:\/\/clone.gimnasticdetarragona.cat\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\/"},"modified":"2016-09-28T19:23:18","modified_gmt":"2016-09-28T19:23:18","slug":"pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota","status":"publish","type":"post","link":"https:\/\/gimnasticdetarragona.cat\/es\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\/","title":{"rendered":"Pelota | 58\u00aa edici\u00f3n del Torneo Santa Tecla de Pelota"},"content":{"rendered":"<p style=\"text-align: justify;\">La secci\u00f3n de pelota del N\u00e0stic organiz\u00f3 el pasado s\u00e1bado una nueva edici\u00f3n del tradicional torneo de Santa Tecla en la pista de front\u00f3n de las instalaciones deportivas del Club Gimn\u00e0stic.<\/p>\n<p style=\"text-align: justify;\">En la 58 edici\u00f3n, enmarcada dentro del programa de la fiesta mayor de la ciudad, se jugaron las finales de frontenis, paleta con pelota de cuero y paleta corta. La jornada se inici\u00f3 a las 9 horas, ante numerosos aficionados y simpatizantes de la secci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">En la modalidad de frontenis, la final la disputaron la pareja formada por Abel Aparicio y Javier Dewisme, ante Jes\u00fas Dom\u00ednguez y Pedro Abell\u00e1n. La final estuvo muy disputada y se tuvo que recurrir al juego de desempate donde se impuso la primera pareja por un claro 10 a 4.<\/p>\n<p style=\"text-align: justify;\">En la modalidad de paleta con pelota de cuero de superveteranos, se volvi\u00f3 a ver a Ra\u00fal Oterino y Luis Manrique sobre la pista, tras la ya lejana retirada de la competici\u00f3n. La pareja rival estaba formada por Nicol\u00e1s Marcos y Pedro Andreu, los cuales ofrecieron un partido entretenido que se llevaron Ra\u00fal y Luis por 2 a 1. El buen papel y juego desplegado por las dos parejas hizo que el p\u00fablico asistente, tras la conclusi\u00f3n del encuentro, los premiara con un gran aplauso.<\/p>\n<p style=\"text-align: justify;\">En cuanto a la pelota de cuero en primera categor\u00eda, las parejas formadas por Nacho Gonz\u00e1lez &#8211; Jaume Pros y Ricard Fresquet &#8211; Miguel S\u00e1nchez fueron los protagonistas de la final. En la disputa de este partido se vieron diferentes alternativas en el marcador disputar, pero finalmente la primera pareja se impuso en dos sets (15 a 14 y 15 a 13).<\/p>\n<p style=\"text-align: justify;\">Por \u00faltimo, en la final de pala corta, la pareja formada por Alberto Dom\u00ednguez y Miguel S\u00e1nchez opusieron resistencia al t\u00e1ndem Nacho G\u00f3nzalez y Ricard Fresquet, pero acabaron cediendo en los dos juegos, ante los amigos y contrincantes.<\/p>\n<p style=\"text-align: justify;\">Tras la conclusi\u00f3n de las respectivas finales de la 58\u00aa edici\u00f3n del Torneo Santa Tecla de Pelota se hizo entrega de los premios a las diferentes parejas ganadoras. Francisco Ferr\u00e9, Vicepresidente del Club Gimn\u00e0stic de Tarragona, y Ra\u00fal Oterino, Vocal de la Secci\u00f3n de Pelota grana, fueron los encargados de hacer la entrega de los galardones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La secci\u00f3n de pelota del N\u00e0stic organiz\u00f3 el pasado s\u00e1bado una nueva edici\u00f3n del tradicional torneo de Santa Tecla en la pista de front\u00f3n de las instalaciones deportivas del Club Gimn\u00e0stic.<\/p>\n","protected":false},"author":1,"featured_media":60612,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[127],"tags":[],"class_list":["post-60615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-secciones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pelota | 58\u00aa edici\u00f3n del Torneo Santa Tecla de Pelota - Gimn\u00e0stic de Tarragona SAD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gimnasticdetarragona.cat\/es\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pelota | 58\u00aa edici\u00f3n del Torneo Santa Tecla de Pelota - Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"og:description\" content=\"La secci\u00f3n de pelota del N\u00e0stic organiz\u00f3 el pasado s\u00e1bado una nueva edici\u00f3n del tradicional torneo de Santa Tecla en la pista de front\u00f3n de las instalaciones deportivas del Club Gimn\u00e0stic.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gimnasticdetarragona.cat\/es\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\/\" \/>\n<meta property=\"og:site_name\" content=\"Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-28T19:23:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05234221113567.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1632\" \/>\n\t<meta property=\"og:image:height\" content=\"916\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"desarrollo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:site\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"desarrollo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\\\/\"},\"author\":{\"name\":\"desarrollo\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\"},\"headline\":\"Pelota | 58\u00aa edici\u00f3n del Torneo Santa Tecla de Pelota\",\"datePublished\":\"2016-09-28T19:23:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\\\/\"},\"wordCount\":394,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/05234221113567.jpg\",\"articleSection\":[\"Secciones\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\\\/\",\"name\":\"Pelota | 58\u00aa edici\u00f3n del Torneo Santa Tecla de Pelota - Gimn\u00e0stic de Tarragona SAD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/05234221113567.jpg\",\"datePublished\":\"2016-09-28T19:23:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/05234221113567.jpg\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/05234221113567.jpg\",\"width\":1632,\"height\":916},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pelota | 58\u00aa edici\u00f3n del Torneo Santa Tecla de Pelota\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"name\":\"Gimn\u00e0stic de Tarragona SAD\",\"description\":\"Gimn\u00e0stic de Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\",\"name\":\"GIMN\u00c0STIC DE TARRAGONA\",\"alternateName\":\"N\u00c0STIC\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"width\":224,\"height\":83,\"caption\":\"GIMN\u00c0STIC DE TARRAGONA\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/NASTICTARRAGONA\",\"https:\\\/\\\/www.instagram.com\\\/nastictarragona\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\",\"name\":\"desarrollo\",\"sameAs\":[\"https:\\\/\\\/clone.gimnasticdetarragona.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pelota | 58\u00aa edici\u00f3n del Torneo Santa Tecla de Pelota - Gimn\u00e0stic de Tarragona SAD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gimnasticdetarragona.cat\/es\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\/","og_locale":"es_ES","og_type":"article","og_title":"Pelota | 58\u00aa edici\u00f3n del Torneo Santa Tecla de Pelota - Gimn\u00e0stic de Tarragona SAD","og_description":"La secci\u00f3n de pelota del N\u00e0stic organiz\u00f3 el pasado s\u00e1bado una nueva edici\u00f3n del tradicional torneo de Santa Tecla en la pista de front\u00f3n de las instalaciones deportivas del Club Gimn\u00e0stic.","og_url":"https:\/\/gimnasticdetarragona.cat\/es\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\/","og_site_name":"Gimn\u00e0stic de Tarragona SAD","article_published_time":"2016-09-28T19:23:18+00:00","og_image":[{"width":1632,"height":916,"url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05234221113567.jpg","type":"image\/jpeg"}],"author":"desarrollo","twitter_card":"summary_large_image","twitter_creator":"@NASTICTARRAGONA","twitter_site":"@NASTICTARRAGONA","twitter_misc":{"Escrito por":"desarrollo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gimnasticdetarragona.cat\/es\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\/#article","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\/"},"author":{"name":"desarrollo","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e"},"headline":"Pelota | 58\u00aa edici\u00f3n del Torneo Santa Tecla de Pelota","datePublished":"2016-09-28T19:23:18+00:00","mainEntityOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\/"},"wordCount":394,"commentCount":0,"publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05234221113567.jpg","articleSection":["Secciones"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gimnasticdetarragona.cat\/es\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\/","url":"https:\/\/gimnasticdetarragona.cat\/es\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\/","name":"Pelota | 58\u00aa edici\u00f3n del Torneo Santa Tecla de Pelota - Gimn\u00e0stic de Tarragona SAD","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\/#primaryimage"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05234221113567.jpg","datePublished":"2016-09-28T19:23:18+00:00","breadcrumb":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gimnasticdetarragona.cat\/es\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\/#primaryimage","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05234221113567.jpg","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/05234221113567.jpg","width":1632,"height":916},{"@type":"BreadcrumbList","@id":"https:\/\/gimnasticdetarragona.cat\/es\/pilota-58ena-edicio-del-torneig-santa-tecla-de-pilota\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/gimnasticdetarragona.cat\/es\/nastic\/"},{"@type":"ListItem","position":2,"name":"Pelota | 58\u00aa edici\u00f3n del Torneo Santa Tecla de Pelota"}]},{"@type":"WebSite","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website","url":"https:\/\/gimnasticdetarragona.cat\/es\/","name":"Gimn\u00e0stic de Tarragona SAD","description":"Gimn\u00e0stic de Tarragona","publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gimnasticdetarragona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization","name":"GIMN\u00c0STIC DE TARRAGONA","alternateName":"N\u00c0STIC","url":"https:\/\/gimnasticdetarragona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","width":224,"height":83,"caption":"GIMN\u00c0STIC DE TARRAGONA"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/NASTICTARRAGONA","https:\/\/www.instagram.com\/nastictarragona\/"]},{"@type":"Person","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e","name":"desarrollo","sameAs":["https:\/\/clone.gimnasticdetarragona.cat"]}]}},"_links":{"self":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/60615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/comments?post=60615"}],"version-history":[{"count":0,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/60615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media\/60612"}],"wp:attachment":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media?parent=60615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/categories?post=60615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/tags?post=60615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}