{"id":63324,"date":"2015-05-06T00:00:00","date_gmt":"2015-05-06T00:00:00","guid":{"rendered":"https:\/\/clone.gimnasticdetarragona.cat\/presentacin-del-nasticamp-estiu-2015\/"},"modified":"2015-05-06T00:00:00","modified_gmt":"2015-05-06T00:00:00","slug":"presentacin-del-nasticamp-estiu-2015","status":"publish","type":"post","link":"https:\/\/gimnasticdetarragona.cat\/es\/presentacin-del-nasticamp-estiu-2015\/","title":{"rendered":"Presentaci&oacute;n del Nasticamp Estiu 2015"},"content":{"rendered":"<p>El Gimn&agrave;stic de Tarragona SAD presenta la segunda edici&oacute;n del Nasticamp Estiu, que tendr&aacute; lugar del 29 de junio al 31 de julio de 2015. El campus va dirigido a todos aquellos ni&ntilde;os y ni&ntilde;as de 5 a 14 a&ntilde;os con ganas de aprender y pasarlo lo bien jugando al f&uacute;tbol.<\/p>\n<p>En esta edici&oacute;n, los participantes del Nasticamp Estiu disfrutar&aacute;n de diferentes actividades de tecnificaci&oacute;n, circuitos t&eacute;cnicos, m&uacute;ltiples torneos de f&uacute;tbol indoor y outdoor, sorteo de regalos, cine de verano, juegos en la playa, acampada, entre otras actividades sorpresa. Adem&aacute;s, cada uno de los participantes recibir&aacute; de regalo un pack de ropa por semana. El precio es desde 110 &euro; la semana y se aplicar&aacute; un 10% de descuento a los jugadores de f&uacute;tbol base y los socios de la entidad.<br \/>\nAparte, en esta edici&oacute;n, los ni&ntilde;os y ni&ntilde;as que hayan participado en anteriores campus podr&aacute;n disfrutar de un 50% de descuento si traen a un amigo que no haya participado anteriormente en ning&uacute;n campus del N&agrave;stic.<\/p>\n<p>&nbsp;<\/p>\n<p>El Nasticamp Estiu 2015 ofrece dos posibilidades a elegir:<br \/>\nOpci&oacute;n 1: Lunes, martes, mi&eacute;rcoles y viernes de 9 a 14h con el desayuno + jueves completo (desayuno, almuerzo, cena y acampada).<br \/>\nOpci&oacute;n 2: Lunes, martes, mi&eacute;rcoles y viernes de 9 a 17h con el desayuno y comida + jueves completo (desayuno, almuerzo, cena y acampada).<br \/>\nSe recuerda que habr&aacute; servicio de acogida gratuito desde las 08:00 horas.<\/p>\n<p>Los precios son los siguientes:<br \/>\nOpci&oacute;n 1: 1 semana 110&euro;, 2 semanas 190&euro;, 3 semanas 275&euro;, 4 semanas 330&euro; y 5 semanas&nbsp;390&euro;.<br \/>\nOpci&oacute;n 2: 1 semana 170&euro;, 2 semanas 290&euro;, 3 semanas 425&euro;, 4 semanas 510&euro; y 5 semanas 600&euro;.<br \/>\nEl acto de presentaci&oacute;n ha contado con la presencia de Jose Luis Deus, director del f&uacute;tbol base, y Jordi Guill&eacute;n, miembro del f&uacute;tbol base del N&agrave;stic.<\/p>\n<p>&nbsp;<\/p>\n<p>Nota: Existe la posibilidad de ampliar el campus dos semanas m&aacute;s, las primeras de agosto, seg&uacute;n la demanda de inscripciones. Los descuentos de las promociones no son acumulables.<\/p>\n<p>Para formalizar la inscripci&oacute;n y\/o m&aacute;s informaci&oacute;n ya pueden dirigirse a las oficinas del N&agrave;stic (9h a 13.30horas y de 16h a 19h), llamando al tel&eacute;fono 977 215 103 o en la web del N&agrave;stic: www.gimnasticdetarragona.cat<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gimn&agrave;stic de Tarragona SAD presenta la segunda edici&oacute;n del Nasticamp Estiu, que tendr&aacute; lugar del 29 de junio al 31 de julio de 2015. El campus va dirigido a todos aquellos ni&ntilde;os y ni&ntilde;as de 5 a 14 a&ntilde;os con ganas de aprender y pasarlo lo bien jugando al f&uacute;tbol. En esta edici&oacute;n, los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":63321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[113],"tags":[],"class_list":["post-63324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentaci&oacute;n del Nasticamp Estiu 2015 - Gimn\u00e0stic de Tarragona SAD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gimnasticdetarragona.cat\/es\/presentacin-del-nasticamp-estiu-2015\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentaci&oacute;n del Nasticamp Estiu 2015 - Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"og:description\" content=\"El Gimn&agrave;stic de Tarragona SAD presenta la segunda edici&oacute;n del Nasticamp Estiu, que tendr&aacute; lugar del 29 de junio al 31 de julio de 2015. El campus va dirigido a todos aquellos ni&ntilde;os y ni&ntilde;as de 5 a 14 a&ntilde;os con ganas de aprender y pasarlo lo bien jugando al f&uacute;tbol. En esta edici&oacute;n, los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gimnasticdetarragona.cat\/es\/presentacin-del-nasticamp-estiu-2015\/\" \/>\n<meta property=\"og:site_name\" content=\"Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-06T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519490672461.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"desarrollo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:site\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"desarrollo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/presentacin-del-nasticamp-estiu-2015\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/presentacin-del-nasticamp-estiu-2015\\\/\"},\"author\":{\"name\":\"desarrollo\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\"},\"headline\":\"Presentaci&oacute;n del Nasticamp Estiu 2015\",\"datePublished\":\"2015-05-06T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/presentacin-del-nasticamp-estiu-2015\\\/\"},\"wordCount\":428,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/presentacin-del-nasticamp-estiu-2015\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/0519490672461.jpg\",\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/presentacin-del-nasticamp-estiu-2015\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/presentacin-del-nasticamp-estiu-2015\\\/\",\"name\":\"Presentaci&oacute;n del Nasticamp Estiu 2015 - Gimn\u00e0stic de Tarragona SAD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/presentacin-del-nasticamp-estiu-2015\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/presentacin-del-nasticamp-estiu-2015\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/0519490672461.jpg\",\"datePublished\":\"2015-05-06T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/presentacin-del-nasticamp-estiu-2015\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/presentacin-del-nasticamp-estiu-2015\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/presentacin-del-nasticamp-estiu-2015\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/0519490672461.jpg\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/0519490672461.jpg\",\"width\":500,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/presentacin-del-nasticamp-estiu-2015\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentaci&oacute;n del Nasticamp Estiu 2015\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"name\":\"Gimn\u00e0stic de Tarragona SAD\",\"description\":\"Gimn\u00e0stic de Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\",\"name\":\"GIMN\u00c0STIC DE TARRAGONA\",\"alternateName\":\"N\u00c0STIC\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"width\":224,\"height\":83,\"caption\":\"GIMN\u00c0STIC DE TARRAGONA\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/NASTICTARRAGONA\",\"https:\\\/\\\/www.instagram.com\\\/nastictarragona\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\",\"name\":\"desarrollo\",\"sameAs\":[\"https:\\\/\\\/clone.gimnasticdetarragona.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentaci&oacute;n del Nasticamp Estiu 2015 - Gimn\u00e0stic de Tarragona SAD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gimnasticdetarragona.cat\/es\/presentacin-del-nasticamp-estiu-2015\/","og_locale":"es_ES","og_type":"article","og_title":"Presentaci&oacute;n del Nasticamp Estiu 2015 - Gimn\u00e0stic de Tarragona SAD","og_description":"El Gimn&agrave;stic de Tarragona SAD presenta la segunda edici&oacute;n del Nasticamp Estiu, que tendr&aacute; lugar del 29 de junio al 31 de julio de 2015. El campus va dirigido a todos aquellos ni&ntilde;os y ni&ntilde;as de 5 a 14 a&ntilde;os con ganas de aprender y pasarlo lo bien jugando al f&uacute;tbol. En esta edici&oacute;n, los [&hellip;]","og_url":"https:\/\/gimnasticdetarragona.cat\/es\/presentacin-del-nasticamp-estiu-2015\/","og_site_name":"Gimn\u00e0stic de Tarragona SAD","article_published_time":"2015-05-06T00:00:00+00:00","og_image":[{"width":500,"height":250,"url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519490672461.jpg","type":"image\/jpeg"}],"author":"desarrollo","twitter_card":"summary_large_image","twitter_creator":"@NASTICTARRAGONA","twitter_site":"@NASTICTARRAGONA","twitter_misc":{"Escrito por":"desarrollo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gimnasticdetarragona.cat\/es\/presentacin-del-nasticamp-estiu-2015\/#article","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/presentacin-del-nasticamp-estiu-2015\/"},"author":{"name":"desarrollo","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e"},"headline":"Presentaci&oacute;n del Nasticamp Estiu 2015","datePublished":"2015-05-06T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/presentacin-del-nasticamp-estiu-2015\/"},"wordCount":428,"commentCount":0,"publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/presentacin-del-nasticamp-estiu-2015\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519490672461.jpg","articleSection":["Actualidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gimnasticdetarragona.cat\/es\/presentacin-del-nasticamp-estiu-2015\/","url":"https:\/\/gimnasticdetarragona.cat\/es\/presentacin-del-nasticamp-estiu-2015\/","name":"Presentaci&oacute;n del Nasticamp Estiu 2015 - Gimn\u00e0stic de Tarragona SAD","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/presentacin-del-nasticamp-estiu-2015\/#primaryimage"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/presentacin-del-nasticamp-estiu-2015\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519490672461.jpg","datePublished":"2015-05-06T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/presentacin-del-nasticamp-estiu-2015\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gimnasticdetarragona.cat\/es\/presentacin-del-nasticamp-estiu-2015\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/presentacin-del-nasticamp-estiu-2015\/#primaryimage","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519490672461.jpg","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519490672461.jpg","width":500,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/gimnasticdetarragona.cat\/es\/presentacin-del-nasticamp-estiu-2015\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/gimnasticdetarragona.cat\/es\/nastic\/"},{"@type":"ListItem","position":2,"name":"Presentaci&oacute;n del Nasticamp Estiu 2015"}]},{"@type":"WebSite","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website","url":"https:\/\/gimnasticdetarragona.cat\/es\/","name":"Gimn\u00e0stic de Tarragona SAD","description":"Gimn\u00e0stic de Tarragona","publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gimnasticdetarragona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization","name":"GIMN\u00c0STIC DE TARRAGONA","alternateName":"N\u00c0STIC","url":"https:\/\/gimnasticdetarragona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","width":224,"height":83,"caption":"GIMN\u00c0STIC DE TARRAGONA"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/NASTICTARRAGONA","https:\/\/www.instagram.com\/nastictarragona\/"]},{"@type":"Person","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e","name":"desarrollo","sameAs":["https:\/\/clone.gimnasticdetarragona.cat"]}]}},"_links":{"self":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/63324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/comments?post=63324"}],"version-history":[{"count":0,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/63324\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media\/63321"}],"wp:attachment":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media?parent=63324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/categories?post=63324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/tags?post=63324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}