{"id":63568,"date":"2015-03-02T00:00:00","date_gmt":"2015-03-02T00:00:00","guid":{"rendered":"https:\/\/clone.gimnasticdetarragona.cat\/nstic-reus-deportiu-domingo-15-a-las-12h\/"},"modified":"2015-03-02T00:00:00","modified_gmt":"2015-03-02T00:00:00","slug":"nstic-reus-deportiu-domingo-15-a-las-12h","status":"publish","type":"post","link":"https:\/\/gimnasticdetarragona.cat\/es\/nstic-reus-deportiu-domingo-15-a-las-12h\/","title":{"rendered":"N&agrave;stic &#8211; Reus Deportiu, domingo 15 a las 12h"},"content":{"rendered":"<p>El partido de liga entre el Gimn&agrave;stic de Tarragona y el Reus Deportiu se disputar&aacute; el pr&oacute;ximo domingo 15 de marzo, a las 12.00 horas, en el Nou Estadi. El partido corresponde a la jornada 29 del grupo III de la Segunda Divisi&oacute;n B.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El partido de liga entre el Gimn&agrave;stic de Tarragona y el Reus Deportiu se disputar&aacute; el pr&oacute;ximo domingo 15 de marzo, a las 12.00 horas, en el Nou Estadi. El partido corresponde a la jornada 29 del grupo III de la Segunda Divisi&oacute;n B.<\/p>\n","protected":false},"author":1,"featured_media":63565,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[113],"tags":[],"class_list":["post-63568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>N&agrave;stic - Reus Deportiu, domingo 15 a las 12h - Gimn\u00e0stic de Tarragona SAD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gimnasticdetarragona.cat\/es\/nstic-reus-deportiu-domingo-15-a-las-12h\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N&agrave;stic - Reus Deportiu, domingo 15 a las 12h - Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"og:description\" content=\"El partido de liga entre el Gimn&agrave;stic de Tarragona y el Reus Deportiu se disputar&aacute; el pr&oacute;ximo domingo 15 de marzo, a las 12.00 horas, en el Nou Estadi. El partido corresponde a la jornada 29 del grupo III de la Segunda Divisi&oacute;n B.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gimnasticdetarragona.cat\/es\/nstic-reus-deportiu-domingo-15-a-las-12h\/\" \/>\n<meta property=\"og:site_name\" content=\"Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-02T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519492972815.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"desarrollo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:site\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"desarrollo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nstic-reus-deportiu-domingo-15-a-las-12h\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nstic-reus-deportiu-domingo-15-a-las-12h\\\/\"},\"author\":{\"name\":\"desarrollo\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\"},\"headline\":\"N&agrave;stic &#8211; Reus Deportiu, domingo 15 a las 12h\",\"datePublished\":\"2015-03-02T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nstic-reus-deportiu-domingo-15-a-las-12h\\\/\"},\"wordCount\":58,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nstic-reus-deportiu-domingo-15-a-las-12h\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/0519492972815.jpg\",\"articleSection\":[\"Actualidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nstic-reus-deportiu-domingo-15-a-las-12h\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nstic-reus-deportiu-domingo-15-a-las-12h\\\/\",\"name\":\"N&agrave;stic - Reus Deportiu, domingo 15 a las 12h - Gimn\u00e0stic de Tarragona SAD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nstic-reus-deportiu-domingo-15-a-las-12h\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nstic-reus-deportiu-domingo-15-a-las-12h\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/0519492972815.jpg\",\"datePublished\":\"2015-03-02T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nstic-reus-deportiu-domingo-15-a-las-12h\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nstic-reus-deportiu-domingo-15-a-las-12h\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nstic-reus-deportiu-domingo-15-a-las-12h\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/0519492972815.jpg\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/0519492972815.jpg\",\"width\":500,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nstic-reus-deportiu-domingo-15-a-las-12h\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"N&agrave;stic &#8211; Reus Deportiu, domingo 15 a las 12h\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"name\":\"Gimn\u00e0stic de Tarragona SAD\",\"description\":\"Gimn\u00e0stic de Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\",\"name\":\"GIMN\u00c0STIC DE TARRAGONA\",\"alternateName\":\"N\u00c0STIC\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"width\":224,\"height\":83,\"caption\":\"GIMN\u00c0STIC DE TARRAGONA\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/NASTICTARRAGONA\",\"https:\\\/\\\/www.instagram.com\\\/nastictarragona\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\",\"name\":\"desarrollo\",\"sameAs\":[\"https:\\\/\\\/clone.gimnasticdetarragona.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N&agrave;stic - Reus Deportiu, domingo 15 a las 12h - Gimn\u00e0stic de Tarragona SAD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gimnasticdetarragona.cat\/es\/nstic-reus-deportiu-domingo-15-a-las-12h\/","og_locale":"es_ES","og_type":"article","og_title":"N&agrave;stic - Reus Deportiu, domingo 15 a las 12h - Gimn\u00e0stic de Tarragona SAD","og_description":"El partido de liga entre el Gimn&agrave;stic de Tarragona y el Reus Deportiu se disputar&aacute; el pr&oacute;ximo domingo 15 de marzo, a las 12.00 horas, en el Nou Estadi. El partido corresponde a la jornada 29 del grupo III de la Segunda Divisi&oacute;n B.","og_url":"https:\/\/gimnasticdetarragona.cat\/es\/nstic-reus-deportiu-domingo-15-a-las-12h\/","og_site_name":"Gimn\u00e0stic de Tarragona SAD","article_published_time":"2015-03-02T00:00:00+00:00","og_image":[{"width":500,"height":250,"url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519492972815.jpg","type":"image\/jpeg"}],"author":"desarrollo","twitter_card":"summary_large_image","twitter_creator":"@NASTICTARRAGONA","twitter_site":"@NASTICTARRAGONA","twitter_misc":{"Escrito por":"desarrollo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gimnasticdetarragona.cat\/es\/nstic-reus-deportiu-domingo-15-a-las-12h\/#article","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/nstic-reus-deportiu-domingo-15-a-las-12h\/"},"author":{"name":"desarrollo","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e"},"headline":"N&agrave;stic &#8211; Reus Deportiu, domingo 15 a las 12h","datePublished":"2015-03-02T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/nstic-reus-deportiu-domingo-15-a-las-12h\/"},"wordCount":58,"commentCount":0,"publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/nstic-reus-deportiu-domingo-15-a-las-12h\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519492972815.jpg","articleSection":["Actualidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gimnasticdetarragona.cat\/es\/nstic-reus-deportiu-domingo-15-a-las-12h\/","url":"https:\/\/gimnasticdetarragona.cat\/es\/nstic-reus-deportiu-domingo-15-a-las-12h\/","name":"N&agrave;stic - Reus Deportiu, domingo 15 a las 12h - Gimn\u00e0stic de Tarragona SAD","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/nstic-reus-deportiu-domingo-15-a-las-12h\/#primaryimage"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/nstic-reus-deportiu-domingo-15-a-las-12h\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519492972815.jpg","datePublished":"2015-03-02T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/nstic-reus-deportiu-domingo-15-a-las-12h\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gimnasticdetarragona.cat\/es\/nstic-reus-deportiu-domingo-15-a-las-12h\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/nstic-reus-deportiu-domingo-15-a-las-12h\/#primaryimage","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519492972815.jpg","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519492972815.jpg","width":500,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/gimnasticdetarragona.cat\/es\/nstic-reus-deportiu-domingo-15-a-las-12h\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/gimnasticdetarragona.cat\/es\/nastic\/"},{"@type":"ListItem","position":2,"name":"N&agrave;stic &#8211; Reus Deportiu, domingo 15 a las 12h"}]},{"@type":"WebSite","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website","url":"https:\/\/gimnasticdetarragona.cat\/es\/","name":"Gimn\u00e0stic de Tarragona SAD","description":"Gimn\u00e0stic de Tarragona","publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gimnasticdetarragona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization","name":"GIMN\u00c0STIC DE TARRAGONA","alternateName":"N\u00c0STIC","url":"https:\/\/gimnasticdetarragona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","width":224,"height":83,"caption":"GIMN\u00c0STIC DE TARRAGONA"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/NASTICTARRAGONA","https:\/\/www.instagram.com\/nastictarragona\/"]},{"@type":"Person","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e","name":"desarrollo","sameAs":["https:\/\/clone.gimnasticdetarragona.cat"]}]}},"_links":{"self":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/63568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/comments?post=63568"}],"version-history":[{"count":0,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/63568\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media\/63565"}],"wp:attachment":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media?parent=63568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/categories?post=63568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/tags?post=63568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}