{"id":64916,"date":"2014-05-13T00:00:00","date_gmt":"2014-05-13T00:00:00","guid":{"rendered":"https:\/\/clone.gimnasticdetarragona.cat\/finaliza-la-temporada-del-ftbol-sala-del-nstic\/"},"modified":"2014-05-13T00:00:00","modified_gmt":"2014-05-13T00:00:00","slug":"finaliza-la-temporada-del-ftbol-sala-del-nstic","status":"publish","type":"post","link":"https:\/\/gimnasticdetarragona.cat\/es\/finaliza-la-temporada-del-ftbol-sala-del-nstic\/","title":{"rendered":"Finaliza la temporada del f&uacute;tbol sala del N&agrave;stic"},"content":{"rendered":"<p>La temporada del f&uacute;tbol sala del N&agrave;stic finaliza, y lo hace despu&eacute;s de unos meses intensos, donde han destacado la capacidad de trabajo y sacrificio de todos aquellos que han tomado parte, los jugadores y cuerpo t&eacute;cnico de cada categor&iacute;a.&nbsp;<\/p>\n<p>Deportivamente, la temporada ha sido complicada, ya que se ha tenido que luchar desde el primer momento desde las posiciones de descenso.Todos&nbsp;los equipos no obstante, han demostrado lucha, sacrificio y dignidad en cada una de las jornadas.&nbsp;<\/p>\n<p>La secci&oacute;n comenz&oacute; con unas plantillas de jugadores y ha acabado pr&aacute;cticamente sin bajas, lo que reafirma la confianza de los jugadores, entrenadores y padres en el club.&nbsp;<\/p>\n<p>El Club Gimn&agrave;stic es el club referente en la ciudad de Tarragona y el resto de provincia. Es por este motivo que desde la secci&oacute;n, se alienta a todos los amantes del f&uacute;tbol sala a seguir formando parte o a inscribirse la pr&oacute;xima temporada para&nbsp;crecer a&ntilde;o tras a&ntilde;o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La temporada del f&uacute;tbol sala del N&agrave;stic finaliza, y lo hace despu&eacute;s de unos meses intensos, donde han destacado la capacidad de trabajo y sacrificio de todos aquellos que han tomado parte, los jugadores y cuerpo t&eacute;cnico de cada categor&iacute;a.&nbsp; Deportivamente, la temporada ha sido complicada, ya que se ha tenido que luchar desde el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":64913,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[113,126,127],"tags":[],"class_list":["post-64916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-primer-equipo","category-secciones"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Finaliza la temporada del f&uacute;tbol sala del N&agrave;stic - Gimn\u00e0stic de Tarragona SAD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gimnasticdetarragona.cat\/es\/finaliza-la-temporada-del-ftbol-sala-del-nstic\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finaliza la temporada del f&uacute;tbol sala del N&agrave;stic - Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"og:description\" content=\"La temporada del f&uacute;tbol sala del N&agrave;stic finaliza, y lo hace despu&eacute;s de unos meses intensos, donde han destacado la capacidad de trabajo y sacrificio de todos aquellos que han tomado parte, los jugadores y cuerpo t&eacute;cnico de cada categor&iacute;a.&nbsp; Deportivamente, la temporada ha sido complicada, ya que se ha tenido que luchar desde el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gimnasticdetarragona.cat\/es\/finaliza-la-temporada-del-ftbol-sala-del-nstic\/\" \/>\n<meta property=\"og:site_name\" content=\"Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-13T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519513574879.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"desarrollo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:site\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"desarrollo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/finaliza-la-temporada-del-ftbol-sala-del-nstic\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/finaliza-la-temporada-del-ftbol-sala-del-nstic\\\/\"},\"author\":{\"name\":\"desarrollo\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\"},\"headline\":\"Finaliza la temporada del f&uacute;tbol sala del N&agrave;stic\",\"datePublished\":\"2014-05-13T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/finaliza-la-temporada-del-ftbol-sala-del-nstic\\\/\"},\"wordCount\":200,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/finaliza-la-temporada-del-ftbol-sala-del-nstic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/0519513574879.jpg\",\"articleSection\":[\"Actualidad\",\"Primer Equipo\",\"Secciones\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/finaliza-la-temporada-del-ftbol-sala-del-nstic\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/finaliza-la-temporada-del-ftbol-sala-del-nstic\\\/\",\"name\":\"Finaliza la temporada del f&uacute;tbol sala del N&agrave;stic - Gimn\u00e0stic de Tarragona SAD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/finaliza-la-temporada-del-ftbol-sala-del-nstic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/finaliza-la-temporada-del-ftbol-sala-del-nstic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/0519513574879.jpg\",\"datePublished\":\"2014-05-13T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/finaliza-la-temporada-del-ftbol-sala-del-nstic\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/finaliza-la-temporada-del-ftbol-sala-del-nstic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/finaliza-la-temporada-del-ftbol-sala-del-nstic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/0519513574879.jpg\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/0519513574879.jpg\",\"width\":500,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/finaliza-la-temporada-del-ftbol-sala-del-nstic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finaliza la temporada del f&uacute;tbol sala del N&agrave;stic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"name\":\"Gimn\u00e0stic de Tarragona SAD\",\"description\":\"Gimn\u00e0stic de Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\",\"name\":\"GIMN\u00c0STIC DE TARRAGONA\",\"alternateName\":\"N\u00c0STIC\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"width\":224,\"height\":83,\"caption\":\"GIMN\u00c0STIC DE TARRAGONA\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/NASTICTARRAGONA\",\"https:\\\/\\\/www.instagram.com\\\/nastictarragona\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\",\"name\":\"desarrollo\",\"sameAs\":[\"https:\\\/\\\/clone.gimnasticdetarragona.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Finaliza la temporada del f&uacute;tbol sala del N&agrave;stic - Gimn\u00e0stic de Tarragona SAD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gimnasticdetarragona.cat\/es\/finaliza-la-temporada-del-ftbol-sala-del-nstic\/","og_locale":"es_ES","og_type":"article","og_title":"Finaliza la temporada del f&uacute;tbol sala del N&agrave;stic - Gimn\u00e0stic de Tarragona SAD","og_description":"La temporada del f&uacute;tbol sala del N&agrave;stic finaliza, y lo hace despu&eacute;s de unos meses intensos, donde han destacado la capacidad de trabajo y sacrificio de todos aquellos que han tomado parte, los jugadores y cuerpo t&eacute;cnico de cada categor&iacute;a.&nbsp; Deportivamente, la temporada ha sido complicada, ya que se ha tenido que luchar desde el [&hellip;]","og_url":"https:\/\/gimnasticdetarragona.cat\/es\/finaliza-la-temporada-del-ftbol-sala-del-nstic\/","og_site_name":"Gimn\u00e0stic de Tarragona SAD","article_published_time":"2014-05-13T00:00:00+00:00","og_image":[{"width":500,"height":250,"url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519513574879.jpg","type":"image\/jpeg"}],"author":"desarrollo","twitter_card":"summary_large_image","twitter_creator":"@NASTICTARRAGONA","twitter_site":"@NASTICTARRAGONA","twitter_misc":{"Escrito por":"desarrollo","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gimnasticdetarragona.cat\/es\/finaliza-la-temporada-del-ftbol-sala-del-nstic\/#article","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/finaliza-la-temporada-del-ftbol-sala-del-nstic\/"},"author":{"name":"desarrollo","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e"},"headline":"Finaliza la temporada del f&uacute;tbol sala del N&agrave;stic","datePublished":"2014-05-13T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/finaliza-la-temporada-del-ftbol-sala-del-nstic\/"},"wordCount":200,"commentCount":0,"publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/finaliza-la-temporada-del-ftbol-sala-del-nstic\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519513574879.jpg","articleSection":["Actualidad","Primer Equipo","Secciones"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gimnasticdetarragona.cat\/es\/finaliza-la-temporada-del-ftbol-sala-del-nstic\/","url":"https:\/\/gimnasticdetarragona.cat\/es\/finaliza-la-temporada-del-ftbol-sala-del-nstic\/","name":"Finaliza la temporada del f&uacute;tbol sala del N&agrave;stic - Gimn\u00e0stic de Tarragona SAD","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/finaliza-la-temporada-del-ftbol-sala-del-nstic\/#primaryimage"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/finaliza-la-temporada-del-ftbol-sala-del-nstic\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519513574879.jpg","datePublished":"2014-05-13T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/finaliza-la-temporada-del-ftbol-sala-del-nstic\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gimnasticdetarragona.cat\/es\/finaliza-la-temporada-del-ftbol-sala-del-nstic\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/finaliza-la-temporada-del-ftbol-sala-del-nstic\/#primaryimage","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519513574879.jpg","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519513574879.jpg","width":500,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/gimnasticdetarragona.cat\/es\/finaliza-la-temporada-del-ftbol-sala-del-nstic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/gimnasticdetarragona.cat\/es\/nastic\/"},{"@type":"ListItem","position":2,"name":"Finaliza la temporada del f&uacute;tbol sala del N&agrave;stic"}]},{"@type":"WebSite","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website","url":"https:\/\/gimnasticdetarragona.cat\/es\/","name":"Gimn\u00e0stic de Tarragona SAD","description":"Gimn\u00e0stic de Tarragona","publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gimnasticdetarragona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization","name":"GIMN\u00c0STIC DE TARRAGONA","alternateName":"N\u00c0STIC","url":"https:\/\/gimnasticdetarragona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","width":224,"height":83,"caption":"GIMN\u00c0STIC DE TARRAGONA"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/NASTICTARRAGONA","https:\/\/www.instagram.com\/nastictarragona\/"]},{"@type":"Person","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e","name":"desarrollo","sameAs":["https:\/\/clone.gimnasticdetarragona.cat"]}]}},"_links":{"self":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/64916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/comments?post=64916"}],"version-history":[{"count":0,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/64916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media\/64913"}],"wp:attachment":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media?parent=64916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/categories?post=64916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/tags?post=64916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}