{"id":67814,"date":"2012-11-16T00:00:00","date_gmt":"2012-11-16T00:00:00","guid":{"rendered":"https:\/\/clone.gimnasticdetarragona.cat\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\/"},"modified":"2012-11-16T00:00:00","modified_gmt":"2012-11-16T00:00:00","slug":"salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad","status":"publish","type":"post","link":"https:\/\/gimnasticdetarragona.cat\/es\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\/","title":{"rendered":"Salamero: &#8216;Ganar para que todo lo que predicamos se haga realidad&#8217;"},"content":{"rendered":"<p>\n\tEl <span>t&eacute;cnico<\/span> del <span>N&agrave;stic<\/span> ha <span>hecho<\/span> <span>este<\/span> <span>mediod&iacute;a<\/span> la <span>rueda<\/span> de <span>prensa<\/span> <span>previa<\/span> al <span>partido<\/span> <span>que<\/span> <span>jugar&aacute;<\/span> el <span>domingo<\/span> a <span>las<\/span> <span>12h<\/span> en el <span>Narc&iacute;s<\/span> <span>Sala<\/span> contra la <span>UE<\/span> <span>Sant<\/span> <span>Andreu<\/span>. El <span>m&aacute;ximo<\/span> <span>responsable<\/span> del <span>banquillo<\/span> <span>grana<\/span> ha <span>dejado<\/span> <span>clara<\/span> la <span>importancia<\/span> <span>que<\/span> <span>tienen<\/span> <span>estos<\/span> <span>tres<\/span> <span>puntos<\/span> <span>para<\/span> los <span>tarraconenses<\/span>, <span>ya<\/span> <span>que<\/span> <span>significar&iacute;an<\/span> la <span>ratificaci&oacute;n<\/span> de <span>todo<\/span> <span>aquello<\/span> <span>por<\/span> lo <span>que<\/span> <span>luchan<\/span> y <span>que<\/span> <span>demostraron<\/span> la <span>semana<\/span> anterior contra el <span>Reus<\/span> <span>Deportiu<\/span>. <span>Salamero<\/span> <span>prev&eacute;<\/span> un <span>partido<\/span> <span>diferente<\/span> al <span>derbi<\/span> y <span>m&aacute;s<\/span> <span>cercano<\/span> al <span>que<\/span> <span>jug&oacute;<\/span> el <span>equipo<\/span> en el <span>campo<\/span> del <span>Prat<\/span> <span>hace<\/span> quince <span>d&iacute;as<\/span>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El t&eacute;cnico del N&agrave;stic ha hecho este mediod&iacute;a la rueda de prensa previa al partido que jugar&aacute; el domingo a las 12h en el Narc&iacute;s Sala contra la UE Sant Andreu. El m&aacute;ximo responsable del banquillo grana ha dejado clara la importancia que tienen estos tres puntos para los tarraconenses, ya que significar&iacute;an la ratificaci&oacute;n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":67811,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[113,126],"tags":[],"class_list":["post-67814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-primer-equipo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salamero: &#039;Ganar para que todo lo que predicamos se haga realidad&#039; - Gimn\u00e0stic de Tarragona SAD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gimnasticdetarragona.cat\/es\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salamero: &#039;Ganar para que todo lo que predicamos se haga realidad&#039; - Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"og:description\" content=\"El t&eacute;cnico del N&agrave;stic ha hecho este mediod&iacute;a la rueda de prensa previa al partido que jugar&aacute; el domingo a las 12h en el Narc&iacute;s Sala contra la UE Sant Andreu. El m&aacute;ximo responsable del banquillo grana ha dejado clara la importancia que tienen estos tres puntos para los tarraconenses, ya que significar&iacute;an la ratificaci&oacute;n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gimnasticdetarragona.cat\/es\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-16T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519470479925.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"desarrollo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:site\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"desarrollo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\\\/\"},\"author\":{\"name\":\"desarrollo\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\"},\"headline\":\"Salamero: &#8216;Ganar para que todo lo que predicamos se haga realidad&#8217;\",\"datePublished\":\"2012-11-16T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\\\/\"},\"wordCount\":127,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/0519470479925.jpg\",\"articleSection\":[\"Actualidad\",\"Primer Equipo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\\\/\",\"name\":\"Salamero: 'Ganar para que todo lo que predicamos se haga realidad' - Gimn\u00e0stic de Tarragona SAD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/0519470479925.jpg\",\"datePublished\":\"2012-11-16T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/0519470479925.jpg\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/0519470479925.jpg\",\"width\":500,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salamero: &#8216;Ganar para que todo lo que predicamos se haga realidad&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"name\":\"Gimn\u00e0stic de Tarragona SAD\",\"description\":\"Gimn\u00e0stic de Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\",\"name\":\"GIMN\u00c0STIC DE TARRAGONA\",\"alternateName\":\"N\u00c0STIC\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"width\":224,\"height\":83,\"caption\":\"GIMN\u00c0STIC DE TARRAGONA\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/NASTICTARRAGONA\",\"https:\\\/\\\/www.instagram.com\\\/nastictarragona\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\",\"name\":\"desarrollo\",\"sameAs\":[\"https:\\\/\\\/clone.gimnasticdetarragona.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salamero: 'Ganar para que todo lo que predicamos se haga realidad' - Gimn\u00e0stic de Tarragona SAD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gimnasticdetarragona.cat\/es\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\/","og_locale":"es_ES","og_type":"article","og_title":"Salamero: 'Ganar para que todo lo que predicamos se haga realidad' - Gimn\u00e0stic de Tarragona SAD","og_description":"El t&eacute;cnico del N&agrave;stic ha hecho este mediod&iacute;a la rueda de prensa previa al partido que jugar&aacute; el domingo a las 12h en el Narc&iacute;s Sala contra la UE Sant Andreu. El m&aacute;ximo responsable del banquillo grana ha dejado clara la importancia que tienen estos tres puntos para los tarraconenses, ya que significar&iacute;an la ratificaci&oacute;n [&hellip;]","og_url":"https:\/\/gimnasticdetarragona.cat\/es\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\/","og_site_name":"Gimn\u00e0stic de Tarragona SAD","article_published_time":"2012-11-16T00:00:00+00:00","og_image":[{"width":500,"height":250,"url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519470479925.jpg","type":"image\/jpeg"}],"author":"desarrollo","twitter_card":"summary_large_image","twitter_creator":"@NASTICTARRAGONA","twitter_site":"@NASTICTARRAGONA","twitter_misc":{"Escrito por":"desarrollo","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gimnasticdetarragona.cat\/es\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\/#article","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\/"},"author":{"name":"desarrollo","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e"},"headline":"Salamero: &#8216;Ganar para que todo lo que predicamos se haga realidad&#8217;","datePublished":"2012-11-16T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\/"},"wordCount":127,"commentCount":0,"publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519470479925.jpg","articleSection":["Actualidad","Primer Equipo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gimnasticdetarragona.cat\/es\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\/","url":"https:\/\/gimnasticdetarragona.cat\/es\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\/","name":"Salamero: 'Ganar para que todo lo que predicamos se haga realidad' - Gimn\u00e0stic de Tarragona SAD","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\/#primaryimage"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519470479925.jpg","datePublished":"2012-11-16T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gimnasticdetarragona.cat\/es\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\/#primaryimage","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519470479925.jpg","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/0519470479925.jpg","width":500,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/gimnasticdetarragona.cat\/es\/salamero-ganar-para-que-todo-lo-que-predicamos-se-haga-realidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/gimnasticdetarragona.cat\/es\/nastic\/"},{"@type":"ListItem","position":2,"name":"Salamero: &#8216;Ganar para que todo lo que predicamos se haga realidad&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website","url":"https:\/\/gimnasticdetarragona.cat\/es\/","name":"Gimn\u00e0stic de Tarragona SAD","description":"Gimn\u00e0stic de Tarragona","publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gimnasticdetarragona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization","name":"GIMN\u00c0STIC DE TARRAGONA","alternateName":"N\u00c0STIC","url":"https:\/\/gimnasticdetarragona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","width":224,"height":83,"caption":"GIMN\u00c0STIC DE TARRAGONA"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/NASTICTARRAGONA","https:\/\/www.instagram.com\/nastictarragona\/"]},{"@type":"Person","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e","name":"desarrollo","sameAs":["https:\/\/clone.gimnasticdetarragona.cat"]}]}},"_links":{"self":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/67814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/comments?post=67814"}],"version-history":[{"count":0,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/67814\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media\/67811"}],"wp:attachment":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media?parent=67814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/categories?post=67814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/tags?post=67814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}