{"id":79330,"date":"2007-09-22T00:00:00","date_gmt":"2007-09-22T00:00:00","guid":{"rendered":"https:\/\/clone.gimnasticdetarragona.cat\/el-nastic-golea-al-poli-ejido\/"},"modified":"2007-09-22T00:00:00","modified_gmt":"2007-09-22T00:00:00","slug":"el-nastic-golea-al-poli-ejido","status":"publish","type":"post","link":"https:\/\/gimnasticdetarragona.cat\/es\/el-nastic-golea-al-poli-ejido\/","title":{"rendered":"El N\u00e0stic golea al Poli Ejido"},"content":{"rendered":"<p>El Gimn\u00e0stic de Tarragona ha ganado por 4 goles a 1 al Poli Ejido, en el retorno de Luis C\u00e9sar en Tarragona. Pese a presentar una alineaci\u00f3n in\u00e9dita debido a las bajas en la defensa, los granas han hecho un inicio de partido espectacular, controlando la pelota y ganando cada dos por tres la espalda a los defensores rivales. Miku, Gorka de Carlos, Campano y Maldonado han sido una pesadilla para el Poli y a los 25 minutos de juego los de Tarragona ya ganaban por 3 a 0, gracias a dos goles de Maldonado (el pitxitxi del equipo) y uno de Campano. El N\u00e0stic se ha limitado a aguantar el marcador hasta la media parte y al empezar la segunda los visitantes han puesto algo de intriga al partido aprovechando una error de posici\u00f3n grana. Javi L\u00f3pez, entonces, ha dado entrada a David S\u00e1nchez y Pinilla y el control del juego ha vuelto a ser local. Pinilla, justo al finalizar el tiempo reglamentario ha puesto el 4 a 1 final. Cabe destacar el ofrecimiento que la plantilla ha hecho de la Copa Catalunya y los actos alrededor del estadio en honor de Santa Tecla.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gimn\u00e0stic de Tarragona ha ganado por 4 goles a 1 al Poli Ejido, en el retorno de Luis C\u00e9sar en Tarragona. Pese a presentar una alineaci\u00f3n in\u00e9dita debido a las bajas en la defensa, los granas han hecho un inicio de partido espectacular, controlando la pelota y ganando cada dos por tres la espalda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[113,126],"tags":[],"class_list":["post-79330","post","type-post","status-publish","format-standard","hentry","category-actualidad","category-primer-equipo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El N\u00e0stic golea al Poli Ejido - Gimn\u00e0stic de Tarragona SAD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gimnasticdetarragona.cat\/el-nastic-goleja-el-poli-ejido\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El N\u00e0stic golea al Poli Ejido - Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"og:description\" content=\"El Gimn\u00e0stic de Tarragona ha ganado por 4 goles a 1 al Poli Ejido, en el retorno de Luis C\u00e9sar en Tarragona. Pese a presentar una alineaci\u00f3n in\u00e9dita debido a las bajas en la defensa, los granas han hecho un inicio de partido espectacular, controlando la pelota y ganando cada dos por tres la espalda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gimnasticdetarragona.cat\/el-nastic-goleja-el-poli-ejido\/\" \/>\n<meta property=\"og:site_name\" content=\"Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"article:published_time\" content=\"2007-09-22T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"desarrollo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:site\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"desarrollo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/el-nastic-goleja-el-poli-ejido\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/el-nastic-goleja-el-poli-ejido\\\/\"},\"author\":{\"name\":\"desarrollo\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\"},\"headline\":\"El N\u00e0stic golea al Poli Ejido\",\"datePublished\":\"2007-09-22T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/el-nastic-goleja-el-poli-ejido\\\/\"},\"wordCount\":203,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"articleSection\":[\"Actualidad\",\"Primer Equipo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/el-nastic-goleja-el-poli-ejido\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/el-nastic-goleja-el-poli-ejido\\\/\",\"name\":\"El N\u00e0stic golea al Poli Ejido - Gimn\u00e0stic de Tarragona SAD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\"},\"datePublished\":\"2007-09-22T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/el-nastic-goleja-el-poli-ejido\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gimnasticdetarragona.cat\\\/el-nastic-goleja-el-poli-ejido\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/el-nastic-goleja-el-poli-ejido\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El N\u00e0stic golea al Poli Ejido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"name\":\"Gimn\u00e0stic de Tarragona SAD\",\"description\":\"Gimn\u00e0stic de Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\",\"name\":\"GIMN\u00c0STIC DE TARRAGONA\",\"alternateName\":\"N\u00c0STIC\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"width\":224,\"height\":83,\"caption\":\"GIMN\u00c0STIC DE TARRAGONA\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/NASTICTARRAGONA\",\"https:\\\/\\\/www.instagram.com\\\/nastictarragona\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\",\"name\":\"desarrollo\",\"sameAs\":[\"https:\\\/\\\/clone.gimnasticdetarragona.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El N\u00e0stic golea al Poli Ejido - Gimn\u00e0stic de Tarragona SAD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gimnasticdetarragona.cat\/el-nastic-goleja-el-poli-ejido\/","og_locale":"es_ES","og_type":"article","og_title":"El N\u00e0stic golea al Poli Ejido - Gimn\u00e0stic de Tarragona SAD","og_description":"El Gimn\u00e0stic de Tarragona ha ganado por 4 goles a 1 al Poli Ejido, en el retorno de Luis C\u00e9sar en Tarragona. Pese a presentar una alineaci\u00f3n in\u00e9dita debido a las bajas en la defensa, los granas han hecho un inicio de partido espectacular, controlando la pelota y ganando cada dos por tres la espalda [&hellip;]","og_url":"https:\/\/gimnasticdetarragona.cat\/el-nastic-goleja-el-poli-ejido\/","og_site_name":"Gimn\u00e0stic de Tarragona SAD","article_published_time":"2007-09-22T00:00:00+00:00","author":"desarrollo","twitter_card":"summary_large_image","twitter_creator":"@NASTICTARRAGONA","twitter_site":"@NASTICTARRAGONA","twitter_misc":{"Escrito por":"desarrollo","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gimnasticdetarragona.cat\/el-nastic-goleja-el-poli-ejido\/#article","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/el-nastic-goleja-el-poli-ejido\/"},"author":{"name":"desarrollo","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e"},"headline":"El N\u00e0stic golea al Poli Ejido","datePublished":"2007-09-22T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/el-nastic-goleja-el-poli-ejido\/"},"wordCount":203,"commentCount":0,"publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"articleSection":["Actualidad","Primer Equipo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gimnasticdetarragona.cat\/el-nastic-goleja-el-poli-ejido\/","url":"https:\/\/gimnasticdetarragona.cat\/el-nastic-goleja-el-poli-ejido\/","name":"El N\u00e0stic golea al Poli Ejido - Gimn\u00e0stic de Tarragona SAD","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website"},"datePublished":"2007-09-22T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/gimnasticdetarragona.cat\/el-nastic-goleja-el-poli-ejido\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gimnasticdetarragona.cat\/el-nastic-goleja-el-poli-ejido\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gimnasticdetarragona.cat\/el-nastic-goleja-el-poli-ejido\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/gimnasticdetarragona.cat\/es\/nastic\/"},{"@type":"ListItem","position":2,"name":"El N\u00e0stic golea al Poli Ejido"}]},{"@type":"WebSite","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website","url":"https:\/\/gimnasticdetarragona.cat\/es\/","name":"Gimn\u00e0stic de Tarragona SAD","description":"Gimn\u00e0stic de Tarragona","publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gimnasticdetarragona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization","name":"GIMN\u00c0STIC DE TARRAGONA","alternateName":"N\u00c0STIC","url":"https:\/\/gimnasticdetarragona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","width":224,"height":83,"caption":"GIMN\u00c0STIC DE TARRAGONA"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/NASTICTARRAGONA","https:\/\/www.instagram.com\/nastictarragona\/"]},{"@type":"Person","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e","name":"desarrollo","sameAs":["https:\/\/clone.gimnasticdetarragona.cat"]}]}},"_links":{"self":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/79330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/comments?post=79330"}],"version-history":[{"count":0,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/79330\/revisions"}],"wp:attachment":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media?parent=79330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/categories?post=79330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/tags?post=79330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}