{"id":79562,"date":"2007-04-08T00:00:00","date_gmt":"2007-04-08T00:00:00","guid":{"rendered":"https:\/\/clone.gimnasticdetarragona.cat\/derrota-injusta-a-riazor-2\/"},"modified":"2007-04-08T00:00:00","modified_gmt":"2007-04-08T00:00:00","slug":"derrota-injusta-a-riazor-2","status":"publish","type":"post","link":"https:\/\/gimnasticdetarragona.cat\/es\/derrota-injusta-a-riazor-2\/","title":{"rendered":"Derrota injusta a Riazor"},"content":{"rendered":"<p>Partidos como los de hoy contra el Deportivo sirven para justificar que el f\u00fatbol no es una ciencia exacta. El N\u00e0stic ha jugado mejor que el Depor, ha tenido m\u00e1s posesi\u00f3n, ha creado m\u00e1s ocasiones y ha perdido por 1 gol a 0 . Desde el primer momento los de Tarragona han pedido la pelota y han intentado hacerse amos del partido, aunque costaba que el dominio se tradujera en ocasiones de gol. El poco peligro ha llegado por las bandas y a pelota parada, pero pese a esto, nada hac\u00eda prever que no fuera posible puntuar en Riazor. Los de Paco Flores han llegado a tener el 65% de posesi\u00f3n en la primera parte, y han cerrado el Deportivo a su campo, que intentaba deshacerse de la presi\u00f3n grana con pelotas largas. El inicio de los segundos 45 minutos han empezado igual, con un N\u00e0stic muy concentrado y un Depor a la defensiva. Pero en el 12&#8242; de la segunda, el \u00e1rbitro ha silbado una falta de Marco muy dudosa a la frontal del \u00e1rea. Iago ha cruzado la pelota de manera magistral y ha hecho in\u00fatil el tir\u00f3n de Bizzarri. Sin protestar, ni cruzar los brazos, el N\u00e0stic se ha multiplicado, y con la entrada de Grahn, Makukula y Gil ha ido de manera descarada por el partido, y es casi inexplicable como no ha conseguido un gol, ya que ha tenido m\u00e1s de 5 ocasiones claras de gol. El empate no ha llegado, y ahora la permanencia se complica, pero no se puede discutir el gran partido que han hecho los hombres de Paco Flores, que han demostrado, que con este juego y entrega, la derrota y los 21 puntos no hacen justicia con la campa\u00f1a de este Gimn\u00e0stic. A\u00fan as\u00ed, las matem\u00e1ticas avalan los granas. Hace falta, pues, seguir luchando hasta el final. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Partidos como los de hoy contra el Deportivo sirven para justificar que el f\u00fatbol no es una ciencia exacta. El N\u00e0stic ha jugado mejor que el Depor, ha tenido m\u00e1s posesi\u00f3n, ha creado m\u00e1s ocasiones y ha perdido por 1 gol a 0 . Desde el primer momento los de Tarragona han pedido la pelota [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[113,126],"tags":[],"class_list":["post-79562","post","type-post","status-publish","format-standard","hentry","category-actualidad","category-primer-equipo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Derrota injusta a Riazor - Gimn\u00e0stic de Tarragona SAD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gimnasticdetarragona.cat\/derrota-injusta-a-riazor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Derrota injusta a Riazor - Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"og:description\" content=\"Partidos como los de hoy contra el Deportivo sirven para justificar que el f\u00fatbol no es una ciencia exacta. El N\u00e0stic ha jugado mejor que el Depor, ha tenido m\u00e1s posesi\u00f3n, ha creado m\u00e1s ocasiones y ha perdido por 1 gol a 0 . Desde el primer momento los de Tarragona han pedido la pelota [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gimnasticdetarragona.cat\/derrota-injusta-a-riazor\/\" \/>\n<meta property=\"og:site_name\" content=\"Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"article:published_time\" content=\"2007-04-08T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"desarrollo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:site\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"desarrollo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/derrota-injusta-a-riazor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/derrota-injusta-a-riazor\\\/\"},\"author\":{\"name\":\"desarrollo\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\"},\"headline\":\"Derrota injusta a Riazor\",\"datePublished\":\"2007-04-08T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/derrota-injusta-a-riazor\\\/\"},\"wordCount\":320,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"articleSection\":[\"Actualidad\",\"Primer Equipo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/derrota-injusta-a-riazor\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/derrota-injusta-a-riazor\\\/\",\"name\":\"Derrota injusta a Riazor - Gimn\u00e0stic de Tarragona SAD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\"},\"datePublished\":\"2007-04-08T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/derrota-injusta-a-riazor\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gimnasticdetarragona.cat\\\/derrota-injusta-a-riazor\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/derrota-injusta-a-riazor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Derrota injusta a Riazor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"name\":\"Gimn\u00e0stic de Tarragona SAD\",\"description\":\"Gimn\u00e0stic de Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\",\"name\":\"GIMN\u00c0STIC DE TARRAGONA\",\"alternateName\":\"N\u00c0STIC\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"width\":224,\"height\":83,\"caption\":\"GIMN\u00c0STIC DE TARRAGONA\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/NASTICTARRAGONA\",\"https:\\\/\\\/www.instagram.com\\\/nastictarragona\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\",\"name\":\"desarrollo\",\"sameAs\":[\"https:\\\/\\\/clone.gimnasticdetarragona.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Derrota injusta a Riazor - Gimn\u00e0stic de Tarragona SAD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gimnasticdetarragona.cat\/derrota-injusta-a-riazor\/","og_locale":"es_ES","og_type":"article","og_title":"Derrota injusta a Riazor - Gimn\u00e0stic de Tarragona SAD","og_description":"Partidos como los de hoy contra el Deportivo sirven para justificar que el f\u00fatbol no es una ciencia exacta. El N\u00e0stic ha jugado mejor que el Depor, ha tenido m\u00e1s posesi\u00f3n, ha creado m\u00e1s ocasiones y ha perdido por 1 gol a 0 . Desde el primer momento los de Tarragona han pedido la pelota [&hellip;]","og_url":"https:\/\/gimnasticdetarragona.cat\/derrota-injusta-a-riazor\/","og_site_name":"Gimn\u00e0stic de Tarragona SAD","article_published_time":"2007-04-08T00:00:00+00:00","author":"desarrollo","twitter_card":"summary_large_image","twitter_creator":"@NASTICTARRAGONA","twitter_site":"@NASTICTARRAGONA","twitter_misc":{"Escrito por":"desarrollo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gimnasticdetarragona.cat\/derrota-injusta-a-riazor\/#article","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/derrota-injusta-a-riazor\/"},"author":{"name":"desarrollo","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e"},"headline":"Derrota injusta a Riazor","datePublished":"2007-04-08T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/derrota-injusta-a-riazor\/"},"wordCount":320,"commentCount":0,"publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"articleSection":["Actualidad","Primer Equipo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gimnasticdetarragona.cat\/derrota-injusta-a-riazor\/","url":"https:\/\/gimnasticdetarragona.cat\/derrota-injusta-a-riazor\/","name":"Derrota injusta a Riazor - Gimn\u00e0stic de Tarragona SAD","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website"},"datePublished":"2007-04-08T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/gimnasticdetarragona.cat\/derrota-injusta-a-riazor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gimnasticdetarragona.cat\/derrota-injusta-a-riazor\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gimnasticdetarragona.cat\/derrota-injusta-a-riazor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/gimnasticdetarragona.cat\/es\/nastic\/"},{"@type":"ListItem","position":2,"name":"Derrota injusta a Riazor"}]},{"@type":"WebSite","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website","url":"https:\/\/gimnasticdetarragona.cat\/es\/","name":"Gimn\u00e0stic de Tarragona SAD","description":"Gimn\u00e0stic de Tarragona","publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gimnasticdetarragona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization","name":"GIMN\u00c0STIC DE TARRAGONA","alternateName":"N\u00c0STIC","url":"https:\/\/gimnasticdetarragona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","width":224,"height":83,"caption":"GIMN\u00c0STIC DE TARRAGONA"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/NASTICTARRAGONA","https:\/\/www.instagram.com\/nastictarragona\/"]},{"@type":"Person","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e","name":"desarrollo","sameAs":["https:\/\/clone.gimnasticdetarragona.cat"]}]}},"_links":{"self":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/79562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/comments?post=79562"}],"version-history":[{"count":0,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/79562\/revisions"}],"wp:attachment":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media?parent=79562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/categories?post=79562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/tags?post=79562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}