{"id":83363,"date":"2021-09-08T19:41:00","date_gmt":"2021-09-08T19:41:00","guid":{"rendered":"https:\/\/clone.gimnasticdetarragona.cat\/nima-automocio-renueva-el-compromiso-con-el-nastic\/"},"modified":"2021-09-08T19:41:00","modified_gmt":"2021-09-08T19:41:00","slug":"nima-automocio-renueva-el-compromiso-con-el-nastic","status":"publish","type":"post","link":"https:\/\/gimnasticdetarragona.cat\/es\/nima-automocio-renueva-el-compromiso-con-el-nastic\/","title":{"rendered":"Nima Automoci\u00f3 renueva el compromiso con el N\u00e0stic"},"content":{"rendered":"<p style=\"text-align: justify;\">El Grupo NIMA, grupo de automoci&oacute;n referente al territorio, renueva su fidelidad grana para continuar apoyando a la entidad en esta nueva temporada en la Primera RFEF.<\/p>\n<p style=\"text-align: justify;\">Los encargados de cerrar el nuevo acuerdo han sido el presidente del N&agrave;stic, Josep Maria Andreu; y el gerente de NIMA Automoci&oacute;, F&eacute;lix Nicol&aacute;s, que han querido sellar el v&iacute;nculo en las instalaciones del Nou Estadi con uno de los nuevos veh&iacute;culos del grupo de automoci&oacute;n, el Mustang Mach-E, que se encuentra dentro de la gama que ofrece Ford Tarraco Center.<\/p>\n<p style=\"text-align: justify;\">Dentro de la renovaci&oacute;n como miembro del Club Empresa del Gimn&agrave;stic de Tarragona, el logotipo de Ford lucir&aacute; los pantalones de juego 2021-2022 del primer equipo y aportar&aacute; vitalidad y experiencia para sumar victorias. En cuanto a los pantalones de entrenamiento, Tarracom&ograve;bil, concesionario oficial de Volkswagen en Tarragona, ser&aacute; el encargado de participar en todas y cada una de las sesiones de trabajo que dirige el t&eacute;cnico Ra&uacute;l Agn&eacute;.<\/p>\n<p style=\"text-align: justify;\">Adem&aacute;s de Ford Tarraco Center y Volkswagen Tarracom&ograve;bil, cabe destacar la importancia de los diferentes concesionarios referencia del territorio pertenecientes al Grupo NIMA y que un a&ntilde;o m&aacute;s apoyan al Gimn&agrave;stic de Tarragona en esta temporada deportiva: Nissan Nikko Center, Jaguar Land Rover Full Traction, Hyundai Augusta Car, Audi Vilam&ograve;bil, Volvo Diselauto Tarraco y Autokolecci&oacute;, todos ellos se suman al proyecto grana para unir esfuerzos y luchar por los objetivos deportivos con la m&aacute;xima confianza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ford Tarraco Center con presencia en el pantal\u00f3n de juego<\/p>\n","protected":false},"author":1,"featured_media":83360,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[113,116,121],"tags":[],"class_list":["post-83363","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-club-empresa","category-home"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nima Automoci\u00f3 renueva el compromiso con el N\u00e0stic - Gimn\u00e0stic de Tarragona SAD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gimnasticdetarragona.cat\/nima-automocio-renova-el-compromis-amb-el-nastic\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nima Automoci\u00f3 renueva el compromiso con el N\u00e0stic - Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"og:description\" content=\"Ford Tarraco Center con presencia en el pantal\u00f3n de juego\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gimnasticdetarragona.cat\/nima-automocio-renova-el-compromis-amb-el-nastic\/\" \/>\n<meta property=\"og:site_name\" content=\"Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-08T19:41:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/08194409web-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1698\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"desarrollo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:site\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"desarrollo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/nima-automocio-renova-el-compromis-amb-el-nastic\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/nima-automocio-renova-el-compromis-amb-el-nastic\\\/\"},\"author\":{\"name\":\"desarrollo\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\"},\"headline\":\"Nima Automoci\u00f3 renueva el compromiso con el N\u00e0stic\",\"datePublished\":\"2021-09-08T19:41:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/nima-automocio-renova-el-compromis-amb-el-nastic\\\/\"},\"wordCount\":285,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/nima-automocio-renova-el-compromis-amb-el-nastic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/08194409web-scaled.jpg\",\"articleSection\":[\"Actualidad\",\"Club Empresa\",\"Home\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/nima-automocio-renova-el-compromis-amb-el-nastic\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/nima-automocio-renova-el-compromis-amb-el-nastic\\\/\",\"name\":\"Nima Automoci\u00f3 renueva el compromiso con el N\u00e0stic - Gimn\u00e0stic de Tarragona SAD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/nima-automocio-renova-el-compromis-amb-el-nastic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/nima-automocio-renova-el-compromis-amb-el-nastic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/08194409web-scaled.jpg\",\"datePublished\":\"2021-09-08T19:41:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/nima-automocio-renova-el-compromis-amb-el-nastic\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gimnasticdetarragona.cat\\\/nima-automocio-renova-el-compromis-amb-el-nastic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/nima-automocio-renova-el-compromis-amb-el-nastic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/08194409web-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/08194409web-scaled.jpg\",\"width\":2560,\"height\":1698},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/nima-automocio-renova-el-compromis-amb-el-nastic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nima Automoci\u00f3 renueva el compromiso con el N\u00e0stic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"name\":\"Gimn\u00e0stic de Tarragona SAD\",\"description\":\"Gimn\u00e0stic de Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\",\"name\":\"GIMN\u00c0STIC DE TARRAGONA\",\"alternateName\":\"N\u00c0STIC\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"width\":224,\"height\":83,\"caption\":\"GIMN\u00c0STIC DE TARRAGONA\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/NASTICTARRAGONA\",\"https:\\\/\\\/www.instagram.com\\\/nastictarragona\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/47b6a637abf88f9bd835540f20ea069e\",\"name\":\"desarrollo\",\"sameAs\":[\"https:\\\/\\\/clone.gimnasticdetarragona.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nima Automoci\u00f3 renueva el compromiso con el N\u00e0stic - Gimn\u00e0stic de Tarragona SAD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gimnasticdetarragona.cat\/nima-automocio-renova-el-compromis-amb-el-nastic\/","og_locale":"es_ES","og_type":"article","og_title":"Nima Automoci\u00f3 renueva el compromiso con el N\u00e0stic - Gimn\u00e0stic de Tarragona SAD","og_description":"Ford Tarraco Center con presencia en el pantal\u00f3n de juego","og_url":"https:\/\/gimnasticdetarragona.cat\/nima-automocio-renova-el-compromis-amb-el-nastic\/","og_site_name":"Gimn\u00e0stic de Tarragona SAD","article_published_time":"2021-09-08T19:41:00+00:00","og_image":[{"width":2560,"height":1698,"url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/08194409web-scaled.jpg","type":"image\/jpeg"}],"author":"desarrollo","twitter_card":"summary_large_image","twitter_creator":"@NASTICTARRAGONA","twitter_site":"@NASTICTARRAGONA","twitter_misc":{"Escrito por":"desarrollo","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gimnasticdetarragona.cat\/nima-automocio-renova-el-compromis-amb-el-nastic\/#article","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/nima-automocio-renova-el-compromis-amb-el-nastic\/"},"author":{"name":"desarrollo","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e"},"headline":"Nima Automoci\u00f3 renueva el compromiso con el N\u00e0stic","datePublished":"2021-09-08T19:41:00+00:00","mainEntityOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/nima-automocio-renova-el-compromis-amb-el-nastic\/"},"wordCount":285,"commentCount":0,"publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/nima-automocio-renova-el-compromis-amb-el-nastic\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/08194409web-scaled.jpg","articleSection":["Actualidad","Club Empresa","Home"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gimnasticdetarragona.cat\/nima-automocio-renova-el-compromis-amb-el-nastic\/","url":"https:\/\/gimnasticdetarragona.cat\/nima-automocio-renova-el-compromis-amb-el-nastic\/","name":"Nima Automoci\u00f3 renueva el compromiso con el N\u00e0stic - Gimn\u00e0stic de Tarragona SAD","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/nima-automocio-renova-el-compromis-amb-el-nastic\/#primaryimage"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/nima-automocio-renova-el-compromis-amb-el-nastic\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/08194409web-scaled.jpg","datePublished":"2021-09-08T19:41:00+00:00","breadcrumb":{"@id":"https:\/\/gimnasticdetarragona.cat\/nima-automocio-renova-el-compromis-amb-el-nastic\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gimnasticdetarragona.cat\/nima-automocio-renova-el-compromis-amb-el-nastic\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/nima-automocio-renova-el-compromis-amb-el-nastic\/#primaryimage","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/08194409web-scaled.jpg","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/08194409web-scaled.jpg","width":2560,"height":1698},{"@type":"BreadcrumbList","@id":"https:\/\/gimnasticdetarragona.cat\/nima-automocio-renova-el-compromis-amb-el-nastic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/gimnasticdetarragona.cat\/es\/nastic\/"},{"@type":"ListItem","position":2,"name":"Nima Automoci\u00f3 renueva el compromiso con el N\u00e0stic"}]},{"@type":"WebSite","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website","url":"https:\/\/gimnasticdetarragona.cat\/es\/","name":"Gimn\u00e0stic de Tarragona SAD","description":"Gimn\u00e0stic de Tarragona","publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gimnasticdetarragona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization","name":"GIMN\u00c0STIC DE TARRAGONA","alternateName":"N\u00c0STIC","url":"https:\/\/gimnasticdetarragona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","width":224,"height":83,"caption":"GIMN\u00c0STIC DE TARRAGONA"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/NASTICTARRAGONA","https:\/\/www.instagram.com\/nastictarragona\/"]},{"@type":"Person","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/47b6a637abf88f9bd835540f20ea069e","name":"desarrollo","sameAs":["https:\/\/clone.gimnasticdetarragona.cat"]}]}},"_links":{"self":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/83363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/comments?post=83363"}],"version-history":[{"count":0,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/83363\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media\/83360"}],"wp:attachment":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media?parent=83363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/categories?post=83363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/tags?post=83363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}