{"id":95115,"date":"2024-03-20T19:44:25","date_gmt":"2024-03-20T18:44:25","guid":{"rendered":"https:\/\/gimnasticdetarragona.cat\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\/"},"modified":"2024-03-20T19:48:33","modified_gmt":"2024-03-20T18:48:33","slug":"events-djs-team-i-pintacares-en-la-previa-de-diumenge","status":"publish","type":"post","link":"https:\/\/gimnasticdetarragona.cat\/es\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\/","title":{"rendered":"Events Dj\u2019s Team y pintacaras en la previa del domingo"},"content":{"rendered":"\n<p>El Gimn\u00e0stic de Tarragona organiza una nueva previa, esta vez con la colaboraci\u00f3n de Events Dj&#8217;s Team. Este domingo, antes del partido ante el Unionistas de Salamanca (20 h), en el exterior del Nou Estadi Costa Daurada se instalar\u00e1 un escenario especial y disfrutaremos de todo tipo de m\u00fasica: a\u00f1os 70&#8217;s, 80&#8217;s, 90&#8217;s, pachanga, Techno, reggaeton\u2026<\/p>\n\n\n\n<p>De la mano de Events Dj&#8217;s Team se amenizar\u00e1 la tarde generando fiesta y alegr\u00eda entre todos los nastiquers presentes y con el objetivo de que sean part\u00edcipes del espect\u00e1culo.<\/p>\n\n\n\n<p>En el exterior del Temple el ambiente empezar\u00e1 a partir de las 17.30 h, con las barras del Bar de l&#8217;Estadi abiertas desde esa misma hora. Y a partir de las 19.15 h, el equipo de Events Dj&#8217;s Team se trasladar\u00e1 al interior del Estadio para continuar la fiesta hasta que arranque el partido. Tambi\u00e9n se ofrecer\u00e1 taller de pintacaras para los m\u00e1s peque\u00f1os.<\/p>\n\n\n\n<p>Adem\u00e1s, en el acceso al torno, todos los socios y aficionados recibir\u00e1n un tarjeta con un n\u00famero para participar en diferentes sorteos de eventos de la empresa Events Dj&#8217;s Team. Estos sorteos se realizar\u00e1n en la media parte del enfrentamiento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de las 17.30 horas, calentamos motores para el N\u00e0stic \u2013 Unionistas de Salamanca<\/p>\n","protected":false},"author":7,"featured_media":95113,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[113,114,125,138],"tags":[],"class_list":["post-95115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-aficion","category-penas","category-socio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Events Dj\u2019s Team y pintacaras en la previa del domingo - Gimn\u00e0stic de Tarragona SAD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gimnasticdetarragona.cat\/es\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Events Dj\u2019s Team y pintacaras en la previa del domingo - Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"og:description\" content=\"A partir de las 17.30 horas, calentamos motores para el N\u00e0stic \u2013 Unionistas de Salamanca\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gimnasticdetarragona.cat\/es\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\/\" \/>\n<meta property=\"og:site_name\" content=\"Gimn\u00e0stic de Tarragona SAD\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-20T18:44:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-20T18:48:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2024\/03\/JCBC8242-copia-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1718\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Comunicacion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:site\" content=\"@NASTICTARRAGONA\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Comunicacion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\\\/\"},\"author\":{\"name\":\"Comunicacion\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/0a9b7103e7dd73640eb245c4aa4afb8d\"},\"headline\":\"Events Dj\u2019s Team y pintacaras en la previa del domingo\",\"datePublished\":\"2024-03-20T18:44:25+00:00\",\"dateModified\":\"2024-03-20T18:48:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\\\/\"},\"wordCount\":217,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/JCBC8242-copia-scaled.jpg\",\"articleSection\":[\"Actualidad\",\"Afici\u00f3n\",\"Pe\u00f1as\",\"Socio\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\\\/\",\"name\":\"Events Dj\u2019s Team y pintacaras en la previa del domingo - Gimn\u00e0stic de Tarragona SAD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/JCBC8242-copia-scaled.jpg\",\"datePublished\":\"2024-03-20T18:44:25+00:00\",\"dateModified\":\"2024-03-20T18:48:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/JCBC8242-copia-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/JCBC8242-copia-scaled.jpg\",\"width\":2560,\"height\":1718},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/nastic\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events Dj\u2019s Team y pintacaras en la previa del domingo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"name\":\"Gimn\u00e0stic de Tarragona SAD\",\"description\":\"Gimn\u00e0stic de Tarragona\",\"publisher\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#organization\",\"name\":\"GIMN\u00c0STIC DE TARRAGONA\",\"alternateName\":\"N\u00c0STIC\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"contentUrl\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cropped-logo-gimnastic.png\",\"width\":224,\"height\":83,\"caption\":\"GIMN\u00c0STIC DE TARRAGONA\"},\"image\":{\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/NASTICTARRAGONA\",\"https:\\\/\\\/www.instagram.com\\\/nastictarragona\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gimnasticdetarragona.cat\\\/es\\\/#\\\/schema\\\/person\\\/0a9b7103e7dd73640eb245c4aa4afb8d\",\"name\":\"Comunicacion\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Events Dj\u2019s Team y pintacaras en la previa del domingo - Gimn\u00e0stic de Tarragona SAD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gimnasticdetarragona.cat\/es\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\/","og_locale":"es_ES","og_type":"article","og_title":"Events Dj\u2019s Team y pintacaras en la previa del domingo - Gimn\u00e0stic de Tarragona SAD","og_description":"A partir de las 17.30 horas, calentamos motores para el N\u00e0stic \u2013 Unionistas de Salamanca","og_url":"https:\/\/gimnasticdetarragona.cat\/es\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\/","og_site_name":"Gimn\u00e0stic de Tarragona SAD","article_published_time":"2024-03-20T18:44:25+00:00","article_modified_time":"2024-03-20T18:48:33+00:00","og_image":[{"width":2560,"height":1718,"url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2024\/03\/JCBC8242-copia-scaled.jpg","type":"image\/jpeg"}],"author":"Comunicacion","twitter_card":"summary_large_image","twitter_creator":"@NASTICTARRAGONA","twitter_site":"@NASTICTARRAGONA","twitter_misc":{"Escrito por":"Comunicacion","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gimnasticdetarragona.cat\/es\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\/#article","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\/"},"author":{"name":"Comunicacion","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/0a9b7103e7dd73640eb245c4aa4afb8d"},"headline":"Events Dj\u2019s Team y pintacaras en la previa del domingo","datePublished":"2024-03-20T18:44:25+00:00","dateModified":"2024-03-20T18:48:33+00:00","mainEntityOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\/"},"wordCount":217,"commentCount":0,"publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2024\/03\/JCBC8242-copia-scaled.jpg","articleSection":["Actualidad","Afici\u00f3n","Pe\u00f1as","Socio"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gimnasticdetarragona.cat\/es\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\/","url":"https:\/\/gimnasticdetarragona.cat\/es\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\/","name":"Events Dj\u2019s Team y pintacaras en la previa del domingo - Gimn\u00e0stic de Tarragona SAD","isPartOf":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\/#primaryimage"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\/#primaryimage"},"thumbnailUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2024\/03\/JCBC8242-copia-scaled.jpg","datePublished":"2024-03-20T18:44:25+00:00","dateModified":"2024-03-20T18:48:33+00:00","breadcrumb":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gimnasticdetarragona.cat\/es\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\/#primaryimage","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2024\/03\/JCBC8242-copia-scaled.jpg","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2024\/03\/JCBC8242-copia-scaled.jpg","width":2560,"height":1718},{"@type":"BreadcrumbList","@id":"https:\/\/gimnasticdetarragona.cat\/es\/events-djs-team-i-pintacares-en-la-previa-de-diumenge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/gimnasticdetarragona.cat\/es\/nastic\/"},{"@type":"ListItem","position":2,"name":"Events Dj\u2019s Team y pintacaras en la previa del domingo"}]},{"@type":"WebSite","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#website","url":"https:\/\/gimnasticdetarragona.cat\/es\/","name":"Gimn\u00e0stic de Tarragona SAD","description":"Gimn\u00e0stic de Tarragona","publisher":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gimnasticdetarragona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#organization","name":"GIMN\u00c0STIC DE TARRAGONA","alternateName":"N\u00c0STIC","url":"https:\/\/gimnasticdetarragona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","contentUrl":"https:\/\/gimnasticdetarragona.cat\/wp-content\/uploads\/2022\/06\/cropped-logo-gimnastic.png","width":224,"height":83,"caption":"GIMN\u00c0STIC DE TARRAGONA"},"image":{"@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/NASTICTARRAGONA","https:\/\/www.instagram.com\/nastictarragona\/"]},{"@type":"Person","@id":"https:\/\/gimnasticdetarragona.cat\/es\/#\/schema\/person\/0a9b7103e7dd73640eb245c4aa4afb8d","name":"Comunicacion"}]}},"_links":{"self":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/95115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/comments?post=95115"}],"version-history":[{"count":0,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/posts\/95115\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media\/95113"}],"wp:attachment":[{"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/media?parent=95115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/categories?post=95115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gimnasticdetarragona.cat\/es\/wp-json\/wp\/v2\/tags?post=95115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}